{"id":2337,"date":"2015-02-18T13:44:27","date_gmt":"2015-02-18T12:44:27","guid":{"rendered":"http:\/\/it.elds.org\/gesu-cristo-org\/?p=2337"},"modified":"2018-07-31T15:24:26","modified_gmt":"2018-07-31T13:24:26","slug":"come-essere-salvati-dalla-grazia-parte-3","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/","title":{"rendered":"Come essere salvati dalla grazia &#8211; Parte 3"},"content":{"rendered":"<p><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-6033 size-full\" title=\"salvati dalla grazia\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg\" alt=\"uomo ringrazia ges\u00f9\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1-300x172.jpg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1-768x439.jpg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>Come essere salvati dalla grazia. In questo terzo capitolo, sul tema della grazia, finiremo di rispondere alle domande su di essa.<\/p>\n<p>Nelle prime due parti abbiamo parlato di ci\u00f2 che la grazia \u00e8, da dove viene, come si collega all&#8217;espiazione, alla giustificazione e alla santificazione e cos\u00ec via.<\/p>\n<p>L&#8217;ultima domanda, in questa discussione (Come faccio ad essere salvati dalla grazia?) funge da sintesi di tutte le altre questioni che abbiamo discusso, sul tema della grazia.<\/p>\n<h2>La grazia \u00e8 davvero gratuita o ci sono degli obblighi che ne derivano?<\/h2>\n<p>Questa \u00e8 una domanda trabocchetto, dal momento che la risposta ad entrambe le met\u00e0 della domanda \u00e8 s\u00ec.<\/p>\n<p>S\u00ec, la grazia di Dio \u00e8 veramente gratuita, in quanto il dono della salvezza dalla morte eterna e la possibilit\u00e0 dell\u2019esaltazione sono date a tutti, senza alcun vincolo.<\/p>\n<p>Il dono \u00e8 offerto a coloro che amano il Salvatore, cos\u00ec come a coloro che lo odiano.<\/p>\n<p>Non ha messo alcuna clausola sui peccati che si \u00e8 offerto di pagare. Per la resurrezione non dobbiamo fare nulla.<\/p>\n<p>La resurrezione arriva a tutti, come un dono gratuito dell\u2019amore di Ges\u00f9.<\/p>\n<p><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/12\/17\/la-differenza-tra-immortalita-ed-eternita\/\" target=\"_blank\" rel=\"noopener\"> Il raggiungimento dell\u2019esaltazione<\/a>, tuttavia, richiede un notevole sforzo, e una grande quantit\u00e0 di obblighi, da parte nostra, ma l&#8217;offerta non \u00e8 data liberamente. Spetta a noi ricevere questo dono.<\/p>\n<p>Come ho gi\u00e0 detto nella prima parte di questi articoli, Dio non pu\u00f2 perdonare la violazione della legge, solo perch\u00e9 lo vuole. Deve essere effettuato il pagamento per ogni peccato.<\/p>\n<p>Se non accetteremo il pagamento di Cristo per i nostri peccati, dobbiamo soffrire all&#8217;inferno, nella misura delle nostre capacit\u00e0 di fare ammenda per le leggi che noi spezziamo.<\/p>\n<p>Anche allora la Sua grazia prende il sopravvento e ci libera dall\u2019inferno, quando abbiamo effettuato la maggior quantit\u00e0 di pagamento che possiamo, perch\u00e8 noi tutti sappiamo che non possiamo pagare il prezzo pieno, per i nostri peccati.<\/p>\n<p>Quindi, anche nel completa rifiuto della Sua sofferenza per conto nostro, Dio \u00e8 misericordioso e dimostra il Suo amore eterno.<\/p>\n<h2>Devo essere perfetto per ricevere la Sua grazia?<\/h2>\n<p>Cristo doveva essere perfetto per pagare per i nostri peccati, ma non abbiamo bisogno di essere perfetti per ricevere la Sua grazia.<\/p>\n<p>In realt\u00e0, ricevere la grazia di Cristo \u00e8 ci\u00f2 che ci aiuta a diventare interi e spiritualmente sani, il che porta a diventare perfetti. Ricordate che la grazia ha il potere di guarirci nelle nostre infermit\u00e0 spirituali ed emozionali.<\/p>\n<p>Pi\u00f9 pesantemente impariamo a fare affidamento sul potere abilitante e di guarigione della grazia di Dio, pi\u00f9 velocemente il processo di avvicinamento verso la perfezione pu\u00f2 avvenire.<\/p>\n<h2>Come posso ricevere il dono della grazia?<\/h2>\n<p>(Questa \u00e8 la domanda di sintesi in tutta questa discussione)<\/p>\n<p><a href=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2008\/07\/Jesus-Praying-Gethsemane-Mormon.jpg\"><img decoding=\"async\" class=\"alignright size-medium wp-image-503\" src=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2008\/07\/Jesus-Praying-Gethsemane-Mormon-228x300.jpg\" alt=\"Jesus-Praying-Gethsemane-Mormon\" width=\"228\" height=\"300\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2008\/07\/Jesus-Praying-Gethsemane-Mormon-228x300.jpg 228w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2008\/07\/Jesus-Praying-Gethsemane-Mormon.jpg 610w\" sizes=\"(max-width: 228px) 100vw, 228px\" \/><\/a>Questa definizione \u00e8 diversa da tutto il resto del mondo cristiano, dal momento che la nostra comprensione della grazia \u00e8 influenzata pesantemente dalla rivelazione moderna, compresi gli insegnamenti del Libro di Mormon.<\/p>\n<p>Siamo d&#8217;accordo che la grazia \u00e8 gratuita e che \u00e8 offerta all&#8217;umanit\u00e0 da un Dio benevolo.<\/p>\n<p>Noi, inoltre, crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Ma questo funge da punto di separazione tra i Santi degli Ultimi Giorni e alcune altre fedi. Alcuni credono che la fede \u00e8 un atto passivo.<\/p>\n<p>A noi, d&#8217;altra parte, \u00e8 stato insegnato che la fede \u00e8 un principio di potere, un principio che fa s\u00ec che il cambiamento avvenga attraverso le opere relative al nostro mettere in atto le nostre convinzioni.<\/p>\n<p>Entrambe queste definizioni di fede in Cristo come abilitazione e guarigione dovute alla grazia, rendono disponibile un potente catalizzatore per il cambiamento, nella vita di una persona.<\/p>\n<p>Ho gi\u00e0 detto che l&#8217;espiazione di Cristo ha aperto una porta di opportunit\u00e0 per il cambiamento. Senza l&#8217;espiazione, il nostro libero arbitrio avrebbe avuto dei vincoli.<\/p>\n<p>Con l&#8217;espiazione siamo ora in grado di fare delle scelte che cambiano la vita e che ci possono portare a Dio.<\/p>\n<p>Questo ci porta al punto principale su quello che la grazia di Cristo fa per noi. La Sua grazia ci offre sia il cancello, che la strada verso Dio, ma richiede l&#8217;uso del nostro libero arbitrio, per farlo. Non possiamo stare a guardare e aspettare gli sforzi di Cristo, per salvarci.<\/p>\n<p>Egli ha aperto la strada e ha reso possibile il nostro ritorno a casa.<\/p>\n<p>Egli \u00e8 pronto e in attesa che noi scegliamo e facciamo ci\u00f2 che \u00e8 necessario, per ritornare a Lui e al nostro Padre, ma tutto dipende dall&#8217;esercizio della nostra scelta personale e dall&#8217;uso del nostro arbitrio, nello scegliere o meno di accettare la Sua graziosa offerta.<\/p>\n<h2>Essere salvati dalla grazia<\/h2>\n<p>E&#8217; importante ricordare che lo scopo della grazia di Dio \u00e8 quello di aiutare a cambiare quel tipo di persone che possono vivere comodamente con Dio.<\/p>\n<p>Ricordate che la grazia \u00e8 un dono di trasformazione. Per fare questo abbiamo bisogno di fare tutti i cambiamenti necessari, nella nostra vita.<\/p>\n<p>La Sua grazia \u00e8 qui come la spinta che dobbiamo realizzare, per poter compiere ci\u00f2 che non avremmo potuto compiere altrimenti.<\/p>\n<p>oi non possiamo cambiare la natura del nostro cuore, ma la Sua grazia \u00e8 in grado di aiutarci ad attuare questi cambiamenti. Abbiamo bisogno di aiuto per superare le nostre debolezze e la Sua grazia \u00e8 l\u00ec per aiutarci a trasformarle in punti di forza.<\/p>\n<p>Ogni passo del ritorno a casa, avviene attraverso la Sua grazia, il Suo potere di abilitazione e di guarigione ed \u00e8 l\u00ec per aiutarci a fare quei cambiamenti, nella nostra vita, che sono necessari per diventare come Cristo.<\/p>\n<p>Per ricevere il potere curativo di Cristo, dobbiamo essere umili e andare da Lui, per chiedere la Sua guida. Dobbiamo obbedire ai comandamenti e invocare la compagnia dello Spirito Santo, perch\u00e9 ci guidi nei nostri sforzi nel rispettare i comandamenti e fare delle scelte sagge.<\/p>\n<p>Solo quando abbiamo fatto lo sforzo da parte nostra, possiamo ricevere la grazia promessa di crescere in forza di carattere e capacit\u00e0.<\/p>\n<p>Solo quando stiamo esercitando la nostra fede in Cristo, di fronte le nostre lotte personali, per superare le nostre debolezze, il suo potere curativo pu\u00f2 cambiare i nostri cuori e le nostre capacit\u00e0, per trasformare le nostre debolezze in punti di forza.<\/p>\n<p>Uno dei punti che crea un po\u2019 di confusione, su come i Santi degli Ultimi Giorni ricevono la grazia, viene dal Libro di Mormon. In 2 Nefi 25:23 ci viene detto:<\/p>\n<p>\u201cPerch\u00e8 noi lavoriamo con diligenza a scrivere per persuadere i nostri figli, e anche i nostri fratelli, a credere in Cristo, e a riconciliarsi con Dio; poich\u00e9 sappiamo che \u00e8 per grazia che siamo salvati, dopo tutto ci\u00f2 che possiamo fare\u201d.<\/p>\n<p>Questo versetto fa sembrare che dobbiamo esaurire le nostre forze, nel fare tutto ci\u00f2 che possiamo fare, e poi, quando siamo sdraiati sul pavimento, ansimando per lo sforzo, allora, e solo allora, il Signore ci benedice con una certa grazia. Non \u00e8 cos\u00ec che funziona la grazia.<\/p>\n<p>Il Signore \u00e8 pronto e disposto a benedire con la Sua grazia, in qualsiasi momento, ognuno dei Suoi figli, quando siamo disposti a mettere davanti anche il minimo sforzo, per essere degni di una meravigliosa benedizione del genere. Egli \u00e8 ansioso e ci incoraggia a fare del bene.<\/p>\n<p>Durante un Devozionale, il 12 Luglio 2011, fatto alla Brigham Young University di Provo, Brad Wilcox ha fatto questa osservazione circa la potenza continua della grazia di Dio.<\/p>\n<p><a href=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/04\/Nessun-addio-dura-per-sempre.png\"><img decoding=\"async\" class=\"alignright size-medium wp-image-2459\" src=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/04\/Nessun-addio-dura-per-sempre-300x190.png\" alt=\"Nessun addio dura per sempre\" width=\"300\" height=\"190\"><\/a>La grazia non \u00e8 un motore di richiamo che entra in gioco, una volta che il nostro approvvigionamento di carburante \u00e8 esaurito. Piuttosto, \u00e8 la nostra fonte di energia costante.<\/p>\n<p>Non \u00e8 la luce alla fine del tunnel, ma la luce che ci aiuta a muoverci attraverso il tunnel. La grazia non ci raggiunge da qualche parte, lungo la strada. Essa viene ricevuta proprio qui e proprio ora.<\/p>\n<p>Gran parte della grazia di Cristo, la Sua misericordia, il Suo dono per noi, si presenta sotto forma di opportunit\u00e0. Ci vuole il cambiamento personale e l&#8217;impegno, per ricevere la Sua grazia. Questa parte del Suo dono rende possibile, per noi, il diventare divinit\u00e0, e ci offre la forza che ci permette di farlo.<\/p>\n<p>La parte di cui, spesso, non ci rendiamo conto, \u00e8 che il Suo aprire la porta dell\u2019esaltazione, non ci rende degli dei. Essa stabilisce soltanto qual \u00e8 il percorso per diventare tale.<\/p>\n<p>Riceviamo questo dono di possibilit\u00e0 eterne, basandosi su Cristo e pentendoci dei nostri peccati, osservando i comandamenti, avvicinandoci allo Spirito Santo, che \u00e8 il nostro tutor e la nostra guida spirituale, e attraverso il retto vivere, usando il potere di Cristo, che permette di cambiare i nostri cuori e superare le nostre debolezze.<\/p>\n<p>Mettiamo in chiaro anche questo, nel discorso: ci vuole impegno, quindi, per ricevere la grazia di Dio? S\u00ec, di certo, ci vuole. Molto di ci\u00f2 che egli ci offre, in modo incondizionato, \u00e8 l&#8217;opportunit\u00e0 di diventare come Cristo.<\/p>\n<p>Ma dobbiamo scegliere di provare. E&#8217; quando si inizia questa strada che le meraviglie del Suo potere diventano evidenti nella nostra vita, cambiando le nostre capacit\u00e0, e permettendoci di fare di pi\u00f9 di quanto abbiamo mai pensato possibile.<\/p>\n<p>Impariamo ad avere fiducia nella Sua costante attenzione, nell\u2019ascoltare lo Spirito e nel crescere nella fede, nella conoscenza e nella saggezza.<\/p>\n<p>Ricordate che le meraviglie della grazia di Dio, si svolgono nella loro capacit\u00e0 di cambiarci e farci diventare qualcosa di pi\u00f9 di quello che attualmente siamo.<\/p>\n<p>Cristo non pu\u00f2 concedere queste benedizioni a coloro che non sono disposti a percorrere la strada del ritorno a Dio.<\/p>\n<p>Quindi, coloro che non sono disposti a metterci dell\u2019impegno e a sforzarci di imparare ci\u00f2 che riguarda Dio e le sue vie, spesso affermeranno che non vedono alcuna prova della grazia di Dio, nella loro vita.<\/p>\n<p>La grazia di Dio \u00e8 data liberamente a chiunque la voglia veramente, ma alcune parti del Suo potere possono essere date solo a coloro che si qualificano per la loro fede in Cristo, per essere salvati della grazia dobbiamo essere simili a Cristo.<\/p>\n<p><strong>Risorse aggiuntive:<\/strong><\/p>\n<p>Se volete saperne di pi\u00f9, sui mormoni, cliccate <a href=\"http:\/\/mormon.org\/ita\" target=\"_blank\" rel=\"nofollow noopener\">qui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Essere salvati dalla grazia \u00e8 data liberamente a chiunque la voglia veramente<\/p>\n","protected":false},"author":46,"featured_media":6033,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[1005],"class_list":["post-2337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dottrine","tag-grazia-divina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come essere salvati dalla grazia - Parte 3 | gesucristo.org<\/title>\n<meta name=\"description\" content=\"Crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Essere salvati dalla grazia \u00e8 data liberamente a chiunque la voglia veramente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come essere salvati dalla grazia - Parte 3 | gesucristo.org\" \/>\n<meta property=\"og:description\" content=\"Crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Essere salvati dalla grazia \u00e8 data liberamente a chiunque la voglia veramente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-18T12:44:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-31T13:24:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"collaboratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"collaboratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/\"},\"author\":{\"name\":\"collaboratore\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"headline\":\"Come essere salvati dalla grazia &#8211; Parte 3\",\"datePublished\":\"2015-02-18T12:44:27+00:00\",\"dateModified\":\"2018-07-31T13:24:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/\"},\"wordCount\":1636,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/02\\\/grazia-di-dio-1.jpg\",\"keywords\":[\"grazia divina\"],\"articleSection\":[\"Dottrine\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/\",\"name\":\"Come essere salvati dalla grazia - Parte 3 | gesucristo.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/02\\\/grazia-di-dio-1.jpg\",\"datePublished\":\"2015-02-18T12:44:27+00:00\",\"dateModified\":\"2018-07-31T13:24:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"description\":\"Crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Essere salvati dalla grazia \u00e8 data liberamente a chiunque la voglia veramente\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/02\\\/grazia-di-dio-1.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/02\\\/grazia-di-dio-1.jpg\",\"width\":948,\"height\":542,\"caption\":\"salvati dalla grazia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/02\\\/18\\\/come-essere-salvati-dalla-grazia-parte-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Come essere salvati dalla grazia &#8211; Parte 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\",\"name\":\"collaboratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"caption\":\"collaboratore\"},\"description\":\"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/collaboratore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come essere salvati dalla grazia - Parte 3 | gesucristo.org","description":"Crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Essere salvati dalla grazia \u00e8 data liberamente a chiunque la voglia veramente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/","og_locale":"it_IT","og_type":"article","og_title":"Come essere salvati dalla grazia - Parte 3 | gesucristo.org","og_description":"Crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Essere salvati dalla grazia \u00e8 data liberamente a chiunque la voglia veramente","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/","og_site_name":"gesucristo.org","article_published_time":"2015-02-18T12:44:27+00:00","article_modified_time":"2018-07-31T13:24:26+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg","type":"image\/jpeg"}],"author":"collaboratore","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"collaboratore","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/"},"author":{"name":"collaboratore","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"headline":"Come essere salvati dalla grazia &#8211; Parte 3","datePublished":"2015-02-18T12:44:27+00:00","dateModified":"2018-07-31T13:24:26+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/"},"wordCount":1636,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg","keywords":["grazia divina"],"articleSection":["Dottrine"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/","name":"Come essere salvati dalla grazia - Parte 3 | gesucristo.org","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg","datePublished":"2015-02-18T12:44:27+00:00","dateModified":"2018-07-31T13:24:26+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"description":"Crediamo che la grazia debba essere ricevuta attraverso la fede in Cristo. Essere salvati dalla grazia \u00e8 data liberamente a chiunque la voglia veramente","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/02\/grazia-di-dio-1.jpg","width":948,"height":542,"caption":"salvati dalla grazia"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/02\/18\/come-essere-salvati-dalla-grazia-parte-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Come essere salvati dalla grazia &#8211; Parte 3"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9","name":"collaboratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","caption":"collaboratore"},"description":"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/collaboratore\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=2337"}],"version-history":[{"count":8,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2337\/revisions"}],"predecessor-version":[{"id":6035,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2337\/revisions\/6035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/6033"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=2337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=2337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=2337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}