{"id":2655,"date":"2015-06-17T16:26:38","date_gmt":"2015-06-17T14:26:38","guid":{"rendered":"http:\/\/it.elds.org\/gesu-cristo-org\/?p=2655"},"modified":"2018-02-08T11:41:04","modified_gmt":"2018-02-08T10:41:04","slug":"crisi-di-fede","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/","title":{"rendered":"La crisi di fede di Hugh B. Brown"},"content":{"rendered":"<p><em><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-6195 size-full\" title=\"crisi di fede\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg\" alt=\"scrivere una lettera\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown-300x172.jpg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown-768x439.jpg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>La crisi di fede di Hugh B. Brown, lui ha servito come Apostolo e, successivamente, come membro della Prima Presidenza della Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Prima, ha lavorato per un breve periodo di tempo come professore di religione alla Brigham Young University.<\/em><\/p>\n<p><em>Mentre era li, ricevette questa lettera da un caro amico che stava attraversando ci\u00f2 che ora \u00e8 conosciuto come una \u201ccrisi di fede\u201d. Il consiglio che diede in risposta settant\u2019anni fa non \u00e8 mai stato pubblicato, ma \u00e8 pertinente ancora oggi mentre ci sforziamo di mantenerci fedeli.<\/em><\/p>\n<h3>8 novembre 1946<\/h3>\n<p>Mio caro &#8230;.:<\/p>\n<p>Mi ha reso molto felice ricevere la tua lettera del 25 ottobre, e apprezzo molto la confidenza che mi hai mostrato. La rivelazione dei tuoi problemi mentali e spirituali non mi sorprendono, dato che sentivo da un po&#8217; di tempo che le acque della tua anima solitamente placida erano diventate decisamente intorbidite e disturbate.<\/p>\n<p>Saresti sorpreso se ti dicessi che io, pure, ho avuto momenti di perplessit\u00e0, incertezza, e dubbio; che io, pure, ho conosciuto l\u2019oscurit\u00e0, nebbiosit\u00e0, e il freddo della valle in mezzo ai pinnacoli illuminati della fede e della sicurezza, e che solo la memoria delle cime lungo la strada che ho percorso, assieme alla visione alquanto nebbiosa di altri sempre davanti a me mi ha dato il coraggio di arrancare quando ero tentato di \u201cpiantare tutto\u201d, di avvolgermi nella scomoda coperta del dubbio e dell\u2019autocommiserazione e semplicemente di abbandonare il campo. Beh, io ho avuto quell\u2019esperienza.<\/p>\n<p>Ma posso dire questo di positivo, che ogni vetta che ho scalato \u00e8 sembrata pi\u00f9 alta e pi\u00f9 motivante dell\u2019ultima, a causa, almeno in parte penso, dell\u2019oscuro sfondo della valle attraverso la quale sono passato. A volte, i forti contrasti sono i pi\u00f9 rivelatori.<\/p>\n<p>In vista dell\u2019ammissione di cui sopra, non ti aspetterai una discussione o un riassunto sulla fede in Dio e sull\u2019immortalit\u00e0.<\/p>\n<p>Nonostante ci\u00f2, e spero che sia cos\u00ec, un raccontarti di alcune esperienze ed osservazioni personali che potr\u00e0 darti una sensazione di cameratismo e portarti comfort, coraggio, speranza e fede, potr\u00e0 rinnovare in te lo spirito di avventura, di entusiasmo per la ricerca della verit\u00e0.<\/p>\n<h2>Crisi di fede<\/h2>\n<p>Primo, ho scoperto che i periodi di dubbio e scetticismo una vera e propria crisi di fede, di reazioni negative e di miscredenza sono sempre state caratterizzate da oscurit\u00e0, congelamento dello spirito, chiusura mentale, cinismo, e miseria generale, fino al punto in cui di desidera l\u2019oblio; mentre periodi di fede, speranza, e reazioni positive sono stati periodi di ottimismo e allegria, ripieni del desiderio di essere e di diventare, di edificare ed incoraggiare, e di puntare con sicurezza verso qualcosa per diventare ancora pi\u00f9 grande.<\/p>\n<p>Ecco, la vita ha una cadenza, un ritmo, un gusto e un valore, e mi sono gloriato nel pensiero che ho la possibilit\u00e0 di estendere questi benefici e queste gioie e possibilit\u00e0 ai miei figli.<\/p>\n<p>Perci\u00f2, con la visione egoistica della soddisfazione personale, ho scelto di nuotare nel fresco e chiaro ruscello della fede, anzich\u00e9 sguazzare nella torbida, snervante, stagnante palude del dubbio e del cinismo; in altre parole la fede restituisce un dividendo di gioia mentre andiamo avanti.<\/p>\n<p>Mi piace la definizione di fede di Fosdick: \u201cLa fede \u00e8 vedere per credere qualcosa che uno ancora non pu\u00f2 dimostrare, e il valore dell\u2019agire sulla base di quell\u2019intuizione\u201d.<\/p>\n<p>A volte ho dovuto riprendere il controllo di me stesso e comandare alle mie ginocchia di piegarsi, alla mia testa di chinarsi, e al mio spirito di contrirsi. Ma di questo porto testimonianza, che ho avuto vedute pi\u00f9 ampie da inginocchiato che da in piedi. In qualche modo il piegare il ginocchio sembr\u00f2 aprire le serrande dell\u2019anima, e ad aver portato le lenti della fede al punto focale.<\/p>\n<p>Molti prima di te e me si sono chiesti se il pregare non fosse meramente un soliloquio, e se avesse come unica risposta l\u2019eco del suo suono.<\/p>\n<p>Dall\u2019altra parte, tuttavia, la preghiera \u00e8 stata un principio vitale- la fede centrale di milioni di nobili uomini e donne, ed il fatto che \u00e8 stata un\u2019estasi che dura da anni e anni attesta certamente il suo valore, che persevera.<\/p>\n<p>\u00c8 fedelmente ricorrente come l\u2019alba; non \u00e8 un capriccio privato n\u00e9 \u00e8 una mera pia illusione o razionalizzazione.<\/p>\n<p>Sono arrivato alla convinzione, tramite le mie esperienze personali, che la <a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/04\/23\/il-potere-della-preghiera\/\" target=\"_blank\" rel=\"noopener\">preghiera \u00e8 cameratismo con Dio<\/a>; infatti, dubito ch\u2019io sarei stato in grado di attraversare alcune recenti esperienze se non avessi avuto questo rifugio.<\/p>\n<p>Per quanto riguarda il se c\u2019\u00e8 davvero un Dio, non lo discuter\u00f2. Ma io, come te, ho osservato riguardo a me stesso ed ho visto le miriadi di prove di un piano e di uno scopo e di un disegno, e mi sono sgridato per aver persino dubitato dell\u2019esistenza del Disegnatore supremo.<\/p>\n<p>Mi \u00e8 stato detto, e sembrano esserci numerose prove per supportarlo, che la materia \u00e8 indistruttibile, che \u00e8 eterna.<\/p>\n<p>Da giovane, se mi fosse stato detto dal mio insegnante a scuola che il banco su cui scrivevo era indistruttibile, e poi se la scuola fosse bruciata avessi visto le ceneri beffarde di dove prima era il mio banco, avrei senza dubbio avuto una crisi di fede nel mio insegnante: chiaramente di fronte a me stava la prova della sua follia.<\/p>\n<p>Ma pi\u00f9 tardi, alle scuole superiori e all\u2019universit\u00e0, dove nei laboratori ho scoperto come catturare e pesare i gas e gli oli, e le ceneri risultanti da legna bruciata e scoperto che il processo di combustione non ha in realt\u00e0 distrutto nulla, avrei concluso che il mio scetticismo giovanile era solo la prova degli stretti limiti della mia conoscenza.<\/p>\n<p>Da quel momento in poi, l\u2019umilt\u00e0 mi ha spronato ad esitare prima di dubitare le verit\u00e0 che i testimoni di ricerche ed osservazioni avevano stabilito.<\/p>\n<p>La mia anima ricercatrice continua a domandare, ma le mie domande hanno a che fare con i modi di decifrare ed arrivare alla verit\u00e0 e scoprire la relazione tra osservazione e intuizione, tra conoscenza e fede.<\/p>\n<p>Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive, e che la morte non interromper\u00e0 la mia esistenza cosciente.<\/p>\n<h2>Come non trovarsi in una crisi di fede<\/h2>\n<p>Non posso portarmi a credere che mentre il mio banco, materia inanimata quale \u00e8, \u00e8 indistruttibile, mentre il pi\u00f9 prezioso, anzi la cosa pi\u00f9 preziosa ch\u2019io conosca, amore umano e personalit\u00e0, non sia altro che transitorio e temporaneo e debba essere distrutto e raggiungere una fine quando io smetto di reagire fisicamente al mondo che mi circonda.<\/p>\n<p>Quel poco di logica di cui ho maestria, quel poco di conoscenza che ho ottenuto mi vieta di accettare l\u2019ipotesi che gli individui verranno completamente distrutti.<\/p>\n<p>Il semplice &#8220;perch\u00e9 Dio non si avvicina a me o non permette a me di avvicinarmi a Lui, cos\u00ec che tramite i miei sensi fisici io possa conoscerlo&#8221;, io non so. Ma questo io so, ch\u2019Egli ha sintonizzato il mio spirito in modo tale da farmi diventare sensibile e a rispondere quando certi impulsi sono emanati da Lui.<\/p>\n<p>Suppongo che se l\u2019infante non ancora nato potesse parlare, egli si ribellerebbe alla prospettiva della nascita direbbe:<\/p>\n<blockquote><p>\u201cNon posso vivere se mi tiri fuori dal mio ambiente sotto il cuore di mia madre. La mia vita \u00e8 cos\u00ec tanto parte della sua che se ci separi sono sicuro che io morir\u00f2 e smetter\u00f2 di essere\u201d.<\/p><\/blockquote>\n<p>Per\u00f2 quel bimbo, quando nato, si ritrova in un ambiente idoneo ai suoi organi e alle sue funzionalit\u00e0 non ancora sviluppate.<\/p>\n<p>Scopre che qualcuno si \u00e8 preparato alla sua venuta, che c\u2019\u00e8 acqua e cibo e aria per soddisfare il suo stomaco e i suoi polmoni che, nonostante fossero presenti, non erano necessari nel suo stadio prenatale.<\/p>\n<p>Mi chiedo se quando moriamo, non stiamo in realt\u00e0 solamente nascendo in un\u2019altra sfera; personalmente sono abbastanza contento di lasciare il risultato nelle mani dello stesso buon Dio che ha preparato la mia venuta qui, e personalmente credo che potrei avere certi organismi spirituali che funzioneranno interamente solo quando nascer\u00f2 in un ambiente idoneo a loro.<\/p>\n<p><a href=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/huge_b_brown1.png\"><img decoding=\"async\" class=\"aligncenter wp-image-2657 size-full\" title=\"Hugh B. Brown - crisi di fede\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/huge_b_brown1.png\" alt=\"Hugh B. Brown crisi di fede\" width=\"262\" height=\"320\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/huge_b_brown1.png 262w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/huge_b_brown1-246x300.png 246w\" sizes=\"(max-width: 262px) 100vw, 262px\" \/><\/a>Beh, questa lettera \u00e8 gi\u00e0 troppo lunga. Ho promesso all\u2019inizio che non avrei discusso, per\u00f2 temo di essere sul punto di raggiungere almeno il confine del discutere. Voglio che tu sappia, mio caro figlio e fratello, che sono fortemente interessato al tuo futuro e che le crisi di fede sono piuttosto comune.<\/p>\n<p>Credo che i violenti attacchi che sono stati fatti alla tua fede, e sui tuoi poteri di riflessione, e sulla speranza che hai avuto in passato, non siano altro che un test.<\/p>\n<p>Credo fermamente che tu abbia un futuro inusuale, e che a causa delle tue possibilit\u00e0, l\u2019avversario &#8211; perch\u00e9 penso che ci sia un avversario- stia facendo un attacco concreto nei tuoi confronti.<\/p>\n<p>Ti suggerisco di assumere un\u2019attitudine positiva quando parli con gli altri, che ti sforzi a convincerli della realt\u00e0 delle cose in cui hai creduto, di ricercare le prove per supportare questa fede, e penso che sarai sorpreso nello scoprire che ci sono molte pi\u00f9 prove a favore della fede di quante ne possano essere assoldate a supportare la parte negativa.<\/p>\n<p>Attendo con impazienza il momento in cui possiamo visitarci ancora, e spero sar\u00e0 possibile rivederci spesso, dato che ho apprezzato il tuo cameratismo ed associazione con me nel passato. Mando il mio affetto a tua moglie, a tuo figlio e a te, e possa Dio benedirti di vedere attraverso la nebbia e scorgere l\u2019alba.<\/p>\n<p>Sinceramente, il tuo amico e fratello,<\/p>\n<p>Hugh B. Brown.<\/p>\n<p>La crisi di fede di Hugh B. Brown. Una nota da Steve Densley Jr, riguardante la provenienza: ho ricevuto questa lettera da mia nonna. Lei era la segretaria di Hugh B. Brown quando era professore alla BYU.<\/p>\n<p>Le fu chiesto di trascrivere la lettera e di mandarla al destinatario originale, e la lettera le piacque cos\u00ec tanto che chiese se potesse tenerne una copia per se; Hugh B. Brown acconsent\u00ec a farle tenere una copia, a condizione che il nome della persona fosse rimosso.<\/p>\n<p>Una copia scannerizzata di questa lettera \u00e8 pubblicata nel link qua sotto. I lettori vedranno che dopo la linea della firma, c\u2019\u00e8 scritto che \u00e8 stata trascritta da \u2018mlb\u2019, che sta per Mary Lou Dixon, il nome da nubile di mia nonna, ora Mary Lou Taylor.<\/p>\n<p>I lettori vedranno inoltre che ci sono delle scritte a mano nella prima pagina. Sono state fatte da mia nonna, e dicono \u201cFede persa in Dio Immortalit\u00e0 e pronto a piantare tutto\u201d. Sono state fatte delle correzioni minori in questo articolo per migliorarne la lettura.<\/p>\n<p><a href=\"http:\/\/lds.net\/wp-content\/uploads\/2015\/05\/HBBLetter.pdf\" target=\"_blank\" rel=\"nofollow noopener\">Scarica una copia della lettera originale in cui Hugh Brown parla della sua&nbsp;<\/a>crisi di fede (in inglese).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive<\/p>\n","protected":false},"author":46,"featured_media":6195,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[416],"tags":[948],"class_list":["post-2655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fede","tag-racconti-ispirati"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La crisi di fede di Hugh B. Brown un apostolo mormone<\/title>\n<meta name=\"description\" content=\"Crisi di fede Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La crisi di fede di Hugh B. Brown un apostolo mormone\" \/>\n<meta property=\"og:description\" content=\"Crisi di fede Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-17T14:26:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-08T10:41:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"collaboratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"collaboratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/\"},\"author\":{\"name\":\"collaboratore\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"headline\":\"La crisi di fede di Hugh B. Brown\",\"datePublished\":\"2015-06-17T14:26:38+00:00\",\"dateModified\":\"2018-02-08T10:41:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/\"},\"wordCount\":1791,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/06\\\/crisi-di-fede-Hugh-brown.jpg\",\"keywords\":[\"racconti ispirati\"],\"articleSection\":[\"Fede\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/\",\"name\":\"La crisi di fede di Hugh B. Brown un apostolo mormone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/06\\\/crisi-di-fede-Hugh-brown.jpg\",\"datePublished\":\"2015-06-17T14:26:38+00:00\",\"dateModified\":\"2018-02-08T10:41:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"description\":\"Crisi di fede Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/06\\\/crisi-di-fede-Hugh-brown.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/06\\\/crisi-di-fede-Hugh-brown.jpg\",\"width\":948,\"height\":542,\"caption\":\"crisi di fede\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/06\\\/17\\\/crisi-di-fede\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La crisi di fede di Hugh B. Brown\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\",\"name\":\"collaboratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"caption\":\"collaboratore\"},\"description\":\"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/collaboratore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La crisi di fede di Hugh B. Brown un apostolo mormone","description":"Crisi di fede Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/","og_locale":"it_IT","og_type":"article","og_title":"La crisi di fede di Hugh B. Brown un apostolo mormone","og_description":"Crisi di fede Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/","og_site_name":"gesucristo.org","article_published_time":"2015-06-17T14:26:38+00:00","article_modified_time":"2018-02-08T10:41:04+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg","type":"image\/jpeg"}],"author":"collaboratore","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"collaboratore","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/"},"author":{"name":"collaboratore","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"headline":"La crisi di fede di Hugh B. Brown","datePublished":"2015-06-17T14:26:38+00:00","dateModified":"2018-02-08T10:41:04+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/"},"wordCount":1791,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg","keywords":["racconti ispirati"],"articleSection":["Fede"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/","name":"La crisi di fede di Hugh B. Brown un apostolo mormone","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg","datePublished":"2015-06-17T14:26:38+00:00","dateModified":"2018-02-08T10:41:04+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"description":"Crisi di fede Ci sono molte cose che non posso spiegare, ci sono molte cose che non posso capire, di una di queste cose sono certamente sicuro: che Dio vive","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/06\/crisi-di-fede-Hugh-brown.jpg","width":948,"height":542,"caption":"crisi di fede"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/06\/17\/crisi-di-fede\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"La crisi di fede di Hugh B. Brown"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9","name":"collaboratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","caption":"collaboratore"},"description":"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/collaboratore\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=2655"}],"version-history":[{"count":13,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2655\/revisions"}],"predecessor-version":[{"id":6203,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2655\/revisions\/6203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/6195"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=2655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=2655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=2655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}