{"id":2761,"date":"2015-07-11T19:10:54","date_gmt":"2015-07-11T17:10:54","guid":{"rendered":"http:\/\/it.elds.org\/gesu-cristo-org\/?p=2761"},"modified":"2018-07-31T14:47:33","modified_gmt":"2018-07-31T12:47:33","slug":"fede-quando-digiuno","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/","title":{"rendered":"Manchiamo di fede quando non digiuniamo per condizioni mediche?"},"content":{"rendered":"<p><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-6279 size-full\" title=\"digiuno\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg\" alt=\"digiuno5\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5-300x172.jpg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5-768x439.jpg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>Ho letto molte domande e molti commenti in vari forum incluso lds.org, e non ho ancora trovato qualcuno che la pensa come me riguardo al digiuno. Il fatto di non digiunare o di farlo parzialmente a causa di vari motivi di carattere medico, indica una mancanza di fede?<\/p>\n<p>Dopotutto, abbiamo a che fare con un essere onnipotente che pu\u00f2 facilmente prendersi cura di noi durante il nostro digiuno, o no? Grazie per il tuo tempo!<\/p>\n<h2>Fede e digiuno<\/h2>\n<p>Alla conferenza generale mormone pi\u00f9 recente (aprile 2015), il presidente Eyring chiam\u00f2 il digiuno \u201cun comandamento con una promessa meravigliosa per tutti quelli in bisogno e per noi.\u201d<\/p>\n<p>Nonostante ci\u00f2, il digiuno non sembra essere ben compreso tra i Santi degli Ultimi Giorni, e questo \u00e8 in parte a causa dei tempi in cui viviamo.<\/p>\n<p>I nostri corpi sono fatti per sopravvivere in condizioni di scarsit\u00e0 o assenza di cibo, ed \u00e8 in grado di sopravvivere in tali condizioni per alcuni giorni alla volta, ma nonostante ci\u00f2 molte persone nella nostra societ\u00e0 non hanno mai passato pi\u00f9 di ventiquattro ore senza mangiare, e la stragrande maggioranza non ha la pi\u00f9 pallida idea di che cosa significhi essere davvero affamati.<\/p>\n<p>Viviamo in un periodo storico veramente stupefacente e benedetto, ma queste benedizioni ci rendono insensibili a ci\u00f2 che abbiamo.<\/p>\n<p>Il presidente Wilford Woodruff ha detto (che si sappia in giro o meno):<\/p>\n<blockquote><p>\u201c\u00c9 stato detto questa mattina che alcune persone hanno affermato che loro non possono digiunare perch\u00e9 il digiunare gli faceva male alla testa.<\/p>\n<p>Beh, io posso digiunare, e allo stesso modo pu\u00f2 farlo ogni altro uomo; e se mi duole la testa perch\u00e9 cerco di osservare i comandamenti di Dio, lasciatela dolere\u201d<\/p><\/blockquote>\n<p>Nonostante questa citazione sia abbastanza conosciuta tra i Santi (molti pensano sia stato Brigham Young ad averla detta), molti non sanno che la parte del \u201cmal di testa\u201d \u00e8 solo una caratteristica temporanea del digiuno.<\/p>\n<p>Quando iniziamo a digiunare, pu\u00f2 venirci mal di testa le prime due o tre volte, o anche le prime dieci o dodici, ma prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue, e a tutte le altre differenze biologiche causate da un digiuno, e stiamo bene.<\/p>\n<p>Il digiunare richiede sempre qualche piccolo prezzo, anche se si tratta di essere un pochino deboli per non aver mangiato per un giorno intero. Ma \u00e8 giusto che sia cos\u00ec, poich\u00e8 il digiuno \u00e8 stato pensato per essere un sacrificio, e quindi il sacrificare qualcosa di buono (cibo per un giorno) per qualcosa di migliore.<\/p>\n<p>Ma per quanto riguarda quelle persone di salute cagionevole, che se digiunassero sarebbero in pericolo di vita? Io ho citato presidente Woodruff prima, e lo far\u00f2 di nuovo; anzi, queste parole sono immediatamente successive alla citazione di prima:<\/p>\n<blockquote><p>\u201cCi potrebbero essere delle persone la cui salute \u00e8 cos\u00ec delicata e fragile che loro sarebbero danneggiate dal digiunare per pi\u00f9 di ventiquattro ore.<\/p>\n<p>Tali persone sono molto , molto rare; poich\u00e9 per la maggior parte di noi la nostra salute complessiva potrebbe solo migliorare se non mangiassimo per un giorno.<\/p>\n<p>Io credo che se i Santi, e perch\u00e9 no, anche chiunque altro, digiunassero una volta al mese, loro vedrebbero dei veri benefici nella loro salute.\u201d<\/p><\/blockquote>\n<p>Naturalmente, noi possiamo applicare quanto detto a noi stessi, e magari in qualche modo alla nostra famiglia, ma raramente sta a noi dire agli altri quali dovrebbero essere le loro azioni personali; infatti la mia risposta vuole essere una di carattere generale, e non una critica a coloro che hanno paura di digiunare.<\/p>\n<p>Le benedizioni del digiuno sono tante, sono potenti, e sono reali, ma vengono solo a coloro che digiunano.<\/p>\n<p>Quei pochi che davvero non possono digiunare non saranno condannati, anche se naturalmente non <a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2012\/12\/26\/scegliete-la-fede\/\" target=\"_blank\" rel=\"noopener\">riceveranno le benedizioni<\/a> del digiunare; ma il resto di noi dovrebbe fare un esame di coscienza molto attento, prima di dichiararci incapaci di digiunare.<\/p>\n<p>Se scegliamo di rifiutare di obbedire alla legge del digiuno, non riceveremo alcune tra le pi\u00f9 grandi e profonde benedizioni, quelle basate sull\u2019obbedienza a questa legge divina.<\/p>\n<p>Il Libro di Mormon ci insegna riguardo ai quattro figli di re Mosia, i quali sono stati uomini molto malvagi che si sono pentiti e sono diventati uomini con una fede e un potere incredibile (<a href=\"https:\/\/www.lds.org\/scriptures\/bofm\/alma\/17.3?lang=ita\" target=\"_blank\" rel=\"noopener\">Alma 17:3<\/a>):<\/p>\n<blockquote><p>\u201c[I figli di Mosia] si erano dedicati a lungo alla preghiera e al digiuno; avevano dunque lo spirito di profezia e lo spirito di rivelazione, e quando insegnavano, insegnavano con il potere e l&#8217;autorit\u00e0 di Dio.\u201d<\/p><\/blockquote>\n<p>Vogliamo lo spirito di rivelazione e di profezia? Quando insegnammo ai nostri figli, o ai nostri amici in Chiesa, o ai nostri vicini, o in qualsiasi altra occasione in cui dobbiamo insegnare le verit\u00e0 del vangelo, vogliamo insegnare con il potere e l\u2019autorit\u00e0 di Dio?<\/p>\n<p>Se s\u00ec, il modo per ottenere ci\u00f2 \u00e8 molto chiaro: dobbiamo fare come i figli di Mosia, e dedicarci \u201ca lungo alla preghiera e al digiuno.\u201d<\/p>\n<p>Sembra che molti membri non abbiamo imparato ad applicare queste lezioni nelle loro vite; infatti, molte volte, il digiuno della domenica omonima \u00e8 spesso saltato completamente, oppure viene fatto semplicemente saltando la colazione della domenica prima.<\/p>\n<p>Invece, se noi vogliamo le benedizioni promesse, dobbiamo essere disposti a seguire la legge su cui queste benedizioni sono predicate. Questo \u00e8 un esempio molto semplice della legge del sacrifico: sacrifichiamo qualcosa che ci piace per ottenere qualcosa che ci piace di pi\u00f9.<\/p>\n<p>Ho iniziato a scrivere questa risposta riferendomi al discorso della conferenza generale di presidente Eyring, e ora ti invito a leggere quel discorso attentamente, e di usarlo come punto di partenza sul tuo studio riguardo al soggetto.<\/p>\n<p>E digiuna! Se diventerai potente nel digiuno, ti far\u00e0 solo del bene!<\/p>\n<p><iframe width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/1M494q5gLwY?wmode=transparent&amp;rel=0&amp;feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;importanza del digiuno. Il digiuno Quando digiuniamo faciamo un&#8217;offerta a Dio e prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue<\/p>\n","protected":false},"author":46,"featured_media":6279,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[432],"tags":[1031],"class_list":["post-2761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-come-viviamo","tag-digiuno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manchiamo di fede quando non digiuniamo? L&#039;importanza del digiuno<\/title>\n<meta name=\"description\" content=\"Il digiuno Quando digiuniamo faciamo un&#039;offerta a Dio e prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manchiamo di fede quando non digiuniamo? L&#039;importanza del digiuno\" \/>\n<meta property=\"og:description\" content=\"Il digiuno Quando digiuniamo faciamo un&#039;offerta a Dio e prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-11T17:10:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-31T12:47:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"collaboratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"collaboratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/\"},\"author\":{\"name\":\"collaboratore\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"headline\":\"Manchiamo di fede quando non digiuniamo per condizioni mediche?\",\"datePublished\":\"2015-07-11T17:10:54+00:00\",\"dateModified\":\"2018-07-31T12:47:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/\"},\"wordCount\":954,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/07\\\/digiuno5.jpg\",\"keywords\":[\"digiuno\"],\"articleSection\":[\"Come viviamo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/\",\"name\":\"Manchiamo di fede quando non digiuniamo? L'importanza del digiuno\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/07\\\/digiuno5.jpg\",\"datePublished\":\"2015-07-11T17:10:54+00:00\",\"dateModified\":\"2018-07-31T12:47:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"description\":\"Il digiuno Quando digiuniamo faciamo un'offerta a Dio e prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/07\\\/digiuno5.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/07\\\/digiuno5.jpg\",\"width\":948,\"height\":542,\"caption\":\"digiuno5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/07\\\/11\\\/fede-quando-digiuno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manchiamo di fede quando non digiuniamo per condizioni mediche?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\",\"name\":\"collaboratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"caption\":\"collaboratore\"},\"description\":\"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/collaboratore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manchiamo di fede quando non digiuniamo? L'importanza del digiuno","description":"Il digiuno Quando digiuniamo faciamo un'offerta a Dio e prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/","og_locale":"it_IT","og_type":"article","og_title":"Manchiamo di fede quando non digiuniamo? L'importanza del digiuno","og_description":"Il digiuno Quando digiuniamo faciamo un'offerta a Dio e prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/","og_site_name":"gesucristo.org","article_published_time":"2015-07-11T17:10:54+00:00","article_modified_time":"2018-07-31T12:47:33+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg","type":"image\/jpeg"}],"author":"collaboratore","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"collaboratore","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/"},"author":{"name":"collaboratore","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"headline":"Manchiamo di fede quando non digiuniamo per condizioni mediche?","datePublished":"2015-07-11T17:10:54+00:00","dateModified":"2018-07-31T12:47:33+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/"},"wordCount":954,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg","keywords":["digiuno"],"articleSection":["Come viviamo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/","name":"Manchiamo di fede quando non digiuniamo? L'importanza del digiuno","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg","datePublished":"2015-07-11T17:10:54+00:00","dateModified":"2018-07-31T12:47:33+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"description":"Il digiuno Quando digiuniamo faciamo un'offerta a Dio e prima o poi, i nostri corpi si adeguano ai livelli di zuccheri ridotti nel sangue","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/07\/digiuno5.jpg","width":948,"height":542,"caption":"digiuno5"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/07\/11\/fede-quando-digiuno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Manchiamo di fede quando non digiuniamo per condizioni mediche?"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9","name":"collaboratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","caption":"collaboratore"},"description":"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/collaboratore\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=2761"}],"version-history":[{"count":7,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2761\/revisions"}],"predecessor-version":[{"id":6282,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2761\/revisions\/6282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/6279"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=2761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=2761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=2761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}