{"id":2871,"date":"2015-08-25T14:55:09","date_gmt":"2015-08-25T12:55:09","guid":{"rendered":"http:\/\/it.elds.org\/gesu-cristo-org\/?p=2871"},"modified":"2018-07-31T14:42:55","modified_gmt":"2018-07-31T12:42:55","slug":"lavorare-allaperto-e-amarne-ogni-minuto","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/","title":{"rendered":"Immaginate di Lavorare All\u2019aperto e Amarne ogni Minuto"},"content":{"rendered":"<p><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-6368 size-full\" title=\"lavorare all'aperto\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg\" alt=\"esercizio fisico\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto-300x172.jpeg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto-768x439.jpeg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>Immaginate di Lavorare All\u2019aperto e Amarne ogni Minuto.<\/p>\n<p>Siamo venuti sulla terra per ricevere un corpo e la conoscenza. Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all&#8217;aperto.<\/p>\n<p>Indipendentemente dal fatto che siate o meno esperti, quando si tratta di fare esercizi, questo articolo pu\u00f2 aiutarvi a riconoscere il legame tra la forma fisica e la spiritualit\u00e0.<\/p>\n<p>Potreste sentirvi come se il vostro s\u00e9 spirituale e il corpo fisico fossero totalmente differenti. A volte, vi potreste sentire come se essi stessero combattendo l&#8217;uno contro l&#8217;altro.<\/p>\n<h2>Lavorare all&#8217;aperto<\/h2>\n<p>Vi \u00e8 mai capitato un giorno in cui non avevate assolutamente alcuna voglia di fare movimento? Sono sicura che tutti ci siamo sentiti cos\u00ec, ad un certo punto, ma il Padre celeste si aspetta che abbiamo cura dei nostri corpi, e un modo per farlo comprende il diventare fisicamente in forma.<\/p>\n<p>Qui di seguito trovate 5 componenti da includere nel vostro regime di esercizio, che vi aiuteranno a capire il legame tra l&#8217;essere fisicamente in forma e il vostro rapporto spirituale con il Padre celeste.<\/p>\n<p><iframe width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/H-DiJvtmQhk?wmode=transparent&amp;rel=0&amp;feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/p>\n<ol>\n<li>\n<h2>Flessibilit\u00e0 &#8211;&nbsp;Lavorare All\u2019aperto<\/h2>\n<\/li>\n<\/ol>\n<p>Le Scritture insegnano che la nostra anima \u00e8 composta dal nostro corpo e dal nostro spirito. Sono uno: &#8220;E lo spirito e il corpo sono l&#8217;anima dell&#8217;uomo\u201d (<a href=\"https:\/\/www.lds.org\/scriptures\/dc-testament\/dc\/88.15?lang=ita#\" target=\"_blank\" rel=\"noopener\">Dottrina e Alleanze 88:15<\/a>).<\/p>\n<p>Essere fisicamente attivi pu\u00f2 aumentare la nostra fiducia davanti al Signore, migliorare il nostro stato d&#8217;animo ed estendere la nostra durata della vita.<\/p>\n<p>La flessibilit\u00e0 riguarda la gamma di movimenti che una persona pu\u00f2 fare, con tutte le giunture. Aumentare la flessibilit\u00e0 permette ad una persona di avere una maggiore capacit\u00e0 di muoversi liberamente, senza paura di infortuni.<\/p>\n<p>Allo stesso modo in cui i nostri muscoli hanno bisogno di essere allungati e stesi, il Signore si aspetta che allunghiamo il passo spiritualmente.<\/p>\n<p>Lo stretching \u00e8 un modo per preparare il corpo a ricevere meglio le istruzioni che la vostra mente e il vostro spirito stanno inviando. Senza stiramenti prima, il vostro corpo non pu\u00f2 semplicemente essere pronto.<\/p>\n<p>Applicazione al fisico:<\/p>\n<ul>\n<li>Lo yoga \u00e8 un ottimo modo per migliorare la flessibilit\u00e0 e permette di migliorare la capacit\u00e0 di padroneggiare il vostro corpo, attraverso la meditazione e la concentrazione. Incorporate lo yoga nella vostra vita, per migliorare la vostra forma fisica e la vostra spiritualit\u00e0.<\/li>\n<li>Il sistema di allenamento pilates \u00e8 un modo fenomenale per aumentare la forza muscolare e la resistenza. Il pilates comprende esercizi che hanno lo scopo di aumentare la flessibilit\u00e0, aumentando nel contempo la forza.<\/li>\n<li>Ho visto come lo stretching dinamico e statico siano il modo perfetto per iniziare e terminare un allenamento. Molti hanno scoperto che iniziare un allenamento con uno stretching dinamico significa essere in grado di prevenire gli infortuni e rendere la vostra esperienza di esercizio pi\u00f9 divertente.<\/li>\n<\/ul>\n<p>Dopo la fine di un allenamento, prendetevi tempo per allungare i muscoli staticamente: questo non solo aumenta la flessibilit\u00e0, ma pu\u00f2 anche ridurre il dolore.<\/p>\n<p>Applicazione Spirituale: mentre cercate di migliorare la vostra flessibilit\u00e0, chiedetevi come potete migliorarvi fisicamente e spiritualmente. In quali modi posso essere pi\u00f9 flessibile e disposto ad allineare la mia volont\u00e0 con la volont\u00e0 di Dio?<\/p>\n<ol start=\"2\">\n<li>\n<h2>Forza &#8211;&nbsp;Lavorare All\u2019aperto<\/h2>\n<\/li>\n<\/ol>\n<p>La forza di una persona pu\u00f2 essere incrementata attraverso l\u2019intenzionale esercizio ripetitivo.<\/p>\n<p>Durante l&#8217;allenamento che mette sotto pressione la forza, le fibre muscolari si abbattono e si ricostruiscono e questo, a sua volta, aumenta la forza muscolare. In modo simile, Dio ci permette di venire a Lui quando siamo spiritualmente a pezzi, stanchi e affaticati e ci promette di cambiare la nostra debolezza, in punti di forza.<\/p>\n<p>Applicazione al fisico:<\/p>\n<ul>\n<li>Allenare la nostra forza \u00e8 un modo favoloso per aumentare il tono muscolare ed \u00e8 anche un modo incredibile per aumentare il metabolismo, migliorando il tono muscolare e la densit\u00e0 ossea. L\u2019utilizzo di pesi liberi, le macchine per fare i pesi e il vostro stesso peso corporeo, sono ottimi metodi per aumentare la forza muscolare e migliorare la vostra forma fisica generale.<\/li>\n<li>L\u2019allenamento incrociato consente alle persone di diventare esperte in pi\u00f9 di una routine di esercizi o attivit\u00e0 fisica. L\u2019Americanrunning.org dice &#8220;L\u2019allenamento incrociato non solo porta cambiamenti positivi nella forma fisica e riduce il rischio di lesioni, ma pu\u00f2 anche dare all&#8217;atleta nuove motivazioni. Previene la noia dei muscoli, cos\u00ec come della mente. Aiuta a mantenersi in forma e ad affinare i riflessi. Se la variet\u00e0 \u00e8 il &#8220;sale della vita&#8221;, l\u2019allenamento incrociato \u00e8 la &#8220;spezia dell\u2019esercizio.&#8221;<\/li>\n<\/ul>\n<p>Applicazione Spirituale: mentre accoppiate il vostro regime di esercizi alla preghiera significativa e allo studio delle Scritture, fate anche una lista dei vostri punti di forza e di debolezza.<\/p>\n<p>Nello stesso modo in cui state cercando di rafforzare i muscoli, fate un piano specifico per cambiare la vostra debolezza, in forza, utilizzando l\u2019incomparabile potere del Signore.<\/p>\n<p>Studiate ci\u00f2 che le Scritture e gli apostoli e i profeti del Signore hanno detto pi\u00f9 volte, per trasformare le debolezze in punti di forza.<\/p>\n<ol start=\"3\">\n<li>\n<h2>Equilibrio &#8211;&nbsp;Lavorare All\u2019aperto<\/h2>\n<\/li>\n<\/ol>\n<p>Il Signore ci ha rivelato che &#8220;Pertanto, in verit\u00e0 vi dico che tutte le cose per me sono spirituali, e in nessun momento ho dato una legge che fosse temporale; n\u00e9 a qualsiasi uomo, n\u00e9 ai figli degli uomini; n\u00e9 ad Adamo, vostro padre, che ho creato&#8221; (<a href=\"https:\/\/www.lds.org\/scriptures\/dc-testament\/dc\/29.34?lang=ita#\" target=\"_blank\" rel=\"noopener\">Dottrina e Alleanze 29:34<\/a>).<\/p>\n<p>Pertanto, quando ci stiamo esercitando, stiamo migliorando il nostro benessere fisico e contemporaneamente soddisfiamo un comandamento spirituale.<\/p>\n<p>Avere un buon equilibrio migliora il fisico e favorisce una buona comunicazione tra il cervello e i singoli muscoli.<\/p>\n<p>L&#8217;anziano M. Russell Ballard ha fatto questo commento, sulla ricerca dell\u2019equilibrio &#8220;&#8230;molte persone, me compreso, hanno difficolt\u00e0 a trovare il tempo per il riposo sufficiente, l\u2019esercizio fisico e il relax.<\/p>\n<p>Dobbiamo programmare il tempo sul nostro calendario, ogni giorno, per queste attivit\u00e0, se vogliamo godere di una vita sana ed equilibrata. Un buon aspetto fisico migliora la nostra dignit\u00e0 e il rispetto di s\u00e9&#8221;.<\/p>\n<p>Applicazione al fisico:<\/p>\n<ul>\n<li>Plyometrics non \u00e8 un insieme di esercizi che, probabilmente, non farete ogni giorno, ma queste attivit\u00e0 possono migliorare la vostra forma fisica generale. Plyos \u00e8 una combinazione di movimenti esplosivi che migliorano la vostra capacit\u00e0 di saltare e sviluppano di pi\u00f9 i vostri addominali, le gambe, le braccia e i muscoli della schiena.<\/li>\n<li>Il Tai Chi \u00e8 una attivit\u00e0 con un impatto molto basso, che pu\u00f2 essere utile a tutte le et\u00e0. Harvard Health dice quanto segue, riguardo al Tai chi: &#8220;Questa forma gentile di esercizio fisico pu\u00f2 prevenire o alleviare molte malattie dell&#8217;invecchiamento e potrebbe essere la perfetta attivit\u00e0 per il resto della vostra vita. Il Tai Chi \u00e8 spesso descritto come &#8216;meditazione in movimento,&#8217; ma potrebbe essere chiamato &#8216;il farmaco in movimento'&#8221;.<\/li>\n<\/ul>\n<p>Applicazione Spirituale: durante l&#8217;esecuzione di esercizi che migliorano l&#8217;equilibrio, mantenete una preghiera nel vostro cuore e chiedetevi: come posso utilizzare meglio il mio tempo?<\/p>\n<p>Come posso essere incrollabile e lasciare il tempo sufficiente al riposo, all&#8217;esercizio fisico, al lavoro, alla famiglia, al relax e alla ricreazione?<\/p>\n<ol start=\"4\">\n<li>\n<h2>Resistenza (aerobica) &#8211;&nbsp;Lavorare All\u2019aperto<\/h2>\n<\/li>\n<\/ol>\n<p>Il Signore ci ha fatto la promessa che se vivremo la parola di saggezza e ci prenderemo cura dei nostri tabernacoli mortali, allora noi &#8220;&#8230;correremo e non ci stancheremo e cammineremo senza stancarci&#8221; (<a href=\"https:\/\/www.lds.org\/scriptures\/dc-testament\/dc\/89.20?lang=ita#\" target=\"_blank\" rel=\"noopener\">DeA 89:20<\/a>).<\/p>\n<p>Per diversi anni, ho avuto l&#8217;opportunit\u00e0 di giocare a basket, al college in cui sono cresciuta, e ho amato i benefici mentali, emotivi e fisici dell\u2019esercizio.<\/p>\n<p>Ma di recente il mio apprezzamento per la possibilit\u00e0 di allenarmi \u00e8 salito alle stelle, quando ho sofferto di una commozione cerebrale che non mi ha lasciato in grado di esercitarmi.<\/p>\n<p>Ogni forma di movimento mi ha provocato gravi mal di testa, per circa sei mesi. Ero stata informata, dai medici, che il mio tempo per giocare con gli sport di contatto era finito.<\/p>\n<p>Tale notizia mi ha fatto sentire stordita. Fu in quel periodo che ho capito che la mia spiritualit\u00e0 veniva compromessa, quando il mio corpo non veniva adeguatamente curato.<\/p>\n<p>Alla fine, mi \u00e8 stato dato l\u2019ok per iniziare di nuovo ad esercitarmi. E&#8217; stato allora che ho cominciato a notare che, mentre correvo o eseguivo altri esercizi, avrei potuto imparare delle lezioni spirituali.<\/p>\n<p>Correre aveva degli effetti sulla mia crescita spirituale e mi aveva insegnato delle lezioni sui punti di forza, sulla resistenza e sulla perseveranza che non avrei potuto imparare senza l&#8217;esperienza cinestetica.<\/p>\n<p>Applicazione al fisico:<\/p>\n<ul>\n<li>La Mayo Clinic suggerisce che ogni persona &#8220;Faccia almeno 150 minuti a settimana di attivit\u00e0 aerobica moderata o 75 minuti a settimana di vigorosa attivit\u00e0 aerobica&#8230; Si pu\u00f2 fare una combinazione di attivit\u00e0 moderata e vigorosa&#8230; Un moderato esercizio aerobico comprende attivit\u00e0 come camminare a ritmo sostenuto, nuotare e falciare il prato. Un vigoroso esercizio aerobico comprende attivit\u00e0 come corsa e danza aerobica.&#8221;<\/li>\n<\/ul>\n<p>Applicazione Spirituale: durante l&#8217;esecuzione del camminare, nuotare o partecipare ad un&#8217;altra attivit\u00e0 aerobica, riflettete perch\u00e9 ci \u00e8 stato comandato di sopportare. Considerate le seguenti domande e i seguenti suggerimenti.<\/p>\n<p>Proprio come le gare possono essere portate a termine dalle gambe, ricordate che invece di sentirvi sopraffatti dal comando di perseverare fino alla fine, cercate di perseverare fedelmente da Domenica a Domenica.<\/p>\n<p>Abbattete la resistenza spirituale in obiettivi gestibili. Ponetevi la domanda: come si aspetta il Signore che mi comporti, quando mi sforzo di essere coraggioso e sviluppo la resistenza?<\/p>\n<ol start=\"5\">\n<li>\n<h2>Mantenere un programma di esercizio regolare, a lungo termine &#8211;&nbsp;Lavorare All\u2019aperto<\/h2>\n<\/li>\n<\/ol>\n<p>Healthyplace.com riferisce che sembrare e sentirsi meglio fisicamente, attraverso un regolare esercizio fisico, possa influenzare l&#8217;autostima.<\/p>\n<p>Esso suggerisce che &#8220;sentirsi bene aumenta il lavoro dei neurotrasmettitori, come la serotonina, e ci sono molti allenamenti che sono stati creati per edificarvi mentalmente e fisicamente. L&#8217;atto di muovere il corpo aiuta il cervello a diventare pi\u00f9 equilibrato e consapevole delle vostre emozioni.&#8221;<\/p>\n<p>Quindi decidete oggi di essere fisicamente in forma, ma non solo, cercate le lezioni spirituali che potete ottenere attraverso l&#8217;esercizio. Utilizzate questi 5 suggerimenti e sviluppate un piano che sia a misura del vostro stile di vita.<\/p>\n<p>Preparatevi ad imparare lezioni fisiche e spirituali, tramite la forma fisica.<\/p>\n<p>Applicazione al fisico:<\/p>\n<ul>\n<li>Scoprite cosa vuol dire correre e non essere stanchi e camminare senza venir meno.<\/li>\n<li>Mentre vi prendete cura del vostro corpo temporale, la vostra capacit\u00e0 di sentire lo Spirito aumenter\u00e0.<\/li>\n<li>Non concentratevi su quanto lontani siano i vostri obiettivi di fitness personali, invece concentratevi sulla voglia di sentirvi meglio, riposare in modo pi\u00f9 efficace e sentire lo Spirito pi\u00f9 facilmente.<\/li>\n<\/ul>\n<p>Applicazione Spirituale: fate uno sforzo per registrare la lezione spirituale che imparate, mentre vi prendete cura del vostro benessere fisico.<\/p>\n<p>L&#8217;esercizio pu\u00f2 essere un modo per divertirsi e un ottimo modo per costruire legami con coloro che amate, mentre diventate spiritualmente in forma. Cercate di bilanciare famiglia, lavoro, responsabilit\u00e0 della Chiesa ed esercizio fisico. Scoprite il potere dello stretching spirituale e fisico.<\/p>\n<p>Oggi \u00e8 il giorno per iniziare a preparare noi stessi a stare davanti a Dio. Lasciate andare tutto ci\u00f2 che \u00e8 stato, che vi vieta di sentirvi fiduciosi per il vostro sviluppo fisico e spirituale.<\/p>\n<p>Ho sentito alcuni dire: &#8220;sembrare di star bene, sentirsi bene, giocare bene&#8221;. Oggi vi suggeriamo questo mantra, per attivare la vostra determinazione a migliorare la vostra salute generale e il vostro benessere.<\/p>\n<p>Diteci in quali modi avete visto aumentare la vostra fiducia spirituale, mentre vi concentrate sul vostro benessere fisico? Commentate qui sotto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all&#8217;aperto.<\/p>\n","protected":false},"author":46,"featured_media":6368,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[432],"tags":[1001],"class_list":["post-2871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-come-viviamo","tag-salute-e-benessere"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immaginate di lavorare all\u2019aperto e amarne ogni minuto<\/title>\n<meta name=\"description\" content=\"Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all&#039;aperto. Immaginate di lavorare all\u2019aperto e Amarne ogni Minuto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immaginate di lavorare all\u2019aperto e amarne ogni minuto\" \/>\n<meta property=\"og:description\" content=\"Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all&#039;aperto. Immaginate di lavorare all\u2019aperto e Amarne ogni Minuto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-25T12:55:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-31T12:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"collaboratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"collaboratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/\"},\"author\":{\"name\":\"collaboratore\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"headline\":\"Immaginate di Lavorare All\u2019aperto e Amarne ogni Minuto\",\"datePublished\":\"2015-08-25T12:55:09+00:00\",\"dateModified\":\"2018-07-31T12:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/\"},\"wordCount\":1885,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/08\\\/Lavorare-All\u2019aperto.jpeg\",\"keywords\":[\"salute e benessere\"],\"articleSection\":[\"Come viviamo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/\",\"name\":\"Immaginate di lavorare all\u2019aperto e amarne ogni minuto\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/08\\\/Lavorare-All\u2019aperto.jpeg\",\"datePublished\":\"2015-08-25T12:55:09+00:00\",\"dateModified\":\"2018-07-31T12:42:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"description\":\"Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all'aperto. Immaginate di lavorare all\u2019aperto e Amarne ogni Minuto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/08\\\/Lavorare-All\u2019aperto.jpeg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/08\\\/Lavorare-All\u2019aperto.jpeg\",\"width\":948,\"height\":542,\"caption\":\"lavorare all'aperto\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/08\\\/25\\\/lavorare-allaperto-e-amarne-ogni-minuto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Immaginate di Lavorare All\u2019aperto e Amarne ogni Minuto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\",\"name\":\"collaboratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"caption\":\"collaboratore\"},\"description\":\"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/collaboratore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immaginate di lavorare all\u2019aperto e amarne ogni minuto","description":"Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all'aperto. Immaginate di lavorare all\u2019aperto e Amarne ogni Minuto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/","og_locale":"it_IT","og_type":"article","og_title":"Immaginate di lavorare all\u2019aperto e amarne ogni minuto","og_description":"Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all'aperto. Immaginate di lavorare all\u2019aperto e Amarne ogni Minuto","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/","og_site_name":"gesucristo.org","article_published_time":"2015-08-25T12:55:09+00:00","article_modified_time":"2018-07-31T12:42:55+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg","type":"image\/jpeg"}],"author":"collaboratore","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"collaboratore","Tempo di lettura stimato":"9 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/"},"author":{"name":"collaboratore","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"headline":"Immaginate di Lavorare All\u2019aperto e Amarne ogni Minuto","datePublished":"2015-08-25T12:55:09+00:00","dateModified":"2018-07-31T12:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/"},"wordCount":1885,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg","keywords":["salute e benessere"],"articleSection":["Come viviamo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/","name":"Immaginate di lavorare all\u2019aperto e amarne ogni minuto","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg","datePublished":"2015-08-25T12:55:09+00:00","dateModified":"2018-07-31T12:42:55+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"description":"Alcune lezioni fisiche e spirituali possono essere apprese solo attraverso esperienze cinestetiche e quando lavoriamo all'aperto. Immaginate di lavorare all\u2019aperto e Amarne ogni Minuto","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/08\/Lavorare-All\u2019aperto.jpeg","width":948,"height":542,"caption":"lavorare all'aperto"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/08\/25\/lavorare-allaperto-e-amarne-ogni-minuto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Immaginate di Lavorare All\u2019aperto e Amarne ogni Minuto"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9","name":"collaboratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","caption":"collaboratore"},"description":"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/collaboratore\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=2871"}],"version-history":[{"count":11,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2871\/revisions"}],"predecessor-version":[{"id":6374,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/2871\/revisions\/6374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/6368"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=2871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=2871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=2871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}