{"id":3063,"date":"2015-11-03T08:39:47","date_gmt":"2015-11-03T07:39:47","guid":{"rendered":"http:\/\/it.elds.org\/gesu-cristo-org\/?p=3063"},"modified":"2018-07-31T13:02:55","modified_gmt":"2018-07-31T11:02:55","slug":"saro-riunita-ad-un-figlio-che-ho-abortito","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/","title":{"rendered":"Sar\u00f2 Riunita ad un Figlio che ho Abortito?"},"content":{"rendered":"<p><strong><a href=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3064\" title=\"Pericoli Aborto Spontaneo\" src=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg\" alt=\"mamma-e-bimbo\" width=\"600\" height=\"450\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg 640w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby-300x225.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/strong><\/p>\n<p>Ho avuto un aborto spontaneo, 15 anni fa. Mi sono chiesta: sar\u00f2 riunita con questa piccola anima non ancora nata, nella prossima vita?<\/p>\n<h2>Aborto spontaneo<\/h2>\n<p>In primo luogo, mi dispiace per l&#8217;esperienza che hai dovuto vivere. Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare.<\/p>\n<p>Per quanto riguarda la tua domanda: certo, nel caso di bambini che muoiono in tenera et\u00e0, abbiamo delle promesse specifiche, dateci attraverso Joseph Smith e altri profeti, che alla fine ci ricongiungeremo con loro. Ma dove gli aborti sono voluti, la Chiesa di Ges\u00f9 Cristo non \u00e8 stata cos\u00ec chiara.<\/p>\n<p>Suppongo che una delle ragioni di ci\u00f2 \u00e8 che non sappiamo con certezza proprio quando, durante la gravidanza, uno spirito entra nel nuovo corpo. In assenza di specifica rivelazione, la Chiesa, come questione politica, non registra le nascite di bambini nati morti o non fornisce un suggellamento per procura, ai genitori, per loro conto.<\/p>\n<p>Tuttavia, non vi \u00e8 certamente nulla di scorretto nella speranza che un giorno ci si ricongiunger\u00e0 con questi bambini. Un&#8217;autorit\u00e0, Joseph Fielding Smith, ha scritto:<\/p>\n<blockquote><p>&#8220;Non ci sono informazioni fornite dalla rivelazione, per quanto riguarda lo status dei bambini nati morti. Tuttavia, vorrei esprimere la mia opinione personale che dovremmo avere speranza che questi piccoli riceveranno una resurrezione e, poi, ci apparterranno. Non posso evitare di pensare che sia cos\u00ec.<\/p>\n<p>&#8220;Quando una coppia ha un figlio nato morto, noi diamo loro tutto l\u2019aiuto possibile. Abbiamo buone ragioni per sperare. I funerali possono essere tenuti, per questi bambini, se i genitori lo desiderano.<\/p>\n<p>I bambini nati morti non devono essere segnalati n\u00e9 registrati come nascite e morti sui registri della Chiesa, ma si suggerisce che essi vengano registrati dai genitori, nella propria famiglia, con un nome per ogni bambino nato morto&#8221; (Citazione dal discorso &#8220;Il Nostro Bambino non Nato&#8221;, La Stella, Febbraio 2006).<\/p><\/blockquote>\n<p>Parlando per esperienza personale, ho avuto un bel po\u2019 di familiari vicini che hanno subito un aborto e hanno condiviso le loro esperienze con me. Una, in seguito, ha ricevuto delle assicurazioni spirituali molto potenti, per mezzo dello Spirito, che si sarebbe davvero ricongiunta con quel bambino perduto.<\/p>\n<p>Un\u2019altra mi ha detto di aver ricevuto un altrettanto potente conferma spirituale che lo spirito, originariamente previsto per la sua gravidanza, era stato inviato ad un&#8217;altra famiglia, e che tutto andava bene. E una terza, era sicura che il suo feto non avesse mai avuto uno spirito.<\/p>\n<p>Non essendo mai stato in gravidanza, e non avendo familiarit\u00e0 con eventuali insegnamenti autorevoli della Chiesa, su questo argomento, posso solo suggerirti di mantenere una mente aperta, cercare la guida dello Spirito e fare un digiuno, per avere tutte le assicurazioni sacre che puoi ricevere, su questo argomento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00f2 Riunita ad un Figlio che ho Abortito? Ho avuto un aborto spontaneo. Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare. Una gravidanza pericolosa.<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[973],"class_list":["post-3063","post","type-post","status-publish","format-standard","hentry","category-dottrine","tag-aborto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sar\u00f2 Riunita ad un Figlio che ho Abortito? Ho avuto un aborto spontaneo<\/title>\n<meta name=\"description\" content=\"Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare. Una gravidanza pericolosa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sar\u00f2 Riunita ad un Figlio che ho Abortito? Ho avuto un aborto spontaneo\" \/>\n<meta property=\"og:description\" content=\"Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare. Una gravidanza pericolosa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-03T07:39:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-31T11:02:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"collaboratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"collaboratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/\"},\"author\":{\"name\":\"collaboratore\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"headline\":\"Sar\u00f2 Riunita ad un Figlio che ho Abortito?\",\"datePublished\":\"2015-11-03T07:39:47+00:00\",\"dateModified\":\"2018-07-31T11:02:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/\"},\"wordCount\":459,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/11\\\/mother-and-baby.jpg\",\"keywords\":[\"aborto\"],\"articleSection\":[\"Dottrine\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/\",\"name\":\"Sar\u00f2 Riunita ad un Figlio che ho Abortito? Ho avuto un aborto spontaneo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/11\\\/mother-and-baby.jpg\",\"datePublished\":\"2015-11-03T07:39:47+00:00\",\"dateModified\":\"2018-07-31T11:02:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"description\":\"Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare. Una gravidanza pericolosa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#primaryimage\",\"url\":\"http:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/11\\\/mother-and-baby.jpg\",\"contentUrl\":\"http:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2015\\\/11\\\/mother-and-baby.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2015\\\/11\\\/03\\\/saro-riunita-ad-un-figlio-che-ho-abortito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sar\u00f2 Riunita ad un Figlio che ho Abortito?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\",\"name\":\"collaboratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"caption\":\"collaboratore\"},\"description\":\"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/collaboratore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sar\u00f2 Riunita ad un Figlio che ho Abortito? Ho avuto un aborto spontaneo","description":"Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare. Una gravidanza pericolosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/","og_locale":"it_IT","og_type":"article","og_title":"Sar\u00f2 Riunita ad un Figlio che ho Abortito? Ho avuto un aborto spontaneo","og_description":"Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare. Una gravidanza pericolosa.","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/","og_site_name":"gesucristo.org","article_published_time":"2015-11-03T07:39:47+00:00","article_modified_time":"2018-07-31T11:02:55+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg","type":"image\/jpeg"}],"author":"collaboratore","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"collaboratore","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/"},"author":{"name":"collaboratore","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"headline":"Sar\u00f2 Riunita ad un Figlio che ho Abortito?","datePublished":"2015-11-03T07:39:47+00:00","dateModified":"2018-07-31T11:02:55+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/"},"wordCount":459,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#primaryimage"},"thumbnailUrl":"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg","keywords":["aborto"],"articleSection":["Dottrine"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/","name":"Sar\u00f2 Riunita ad un Figlio che ho Abortito? Ho avuto un aborto spontaneo","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#primaryimage"},"thumbnailUrl":"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg","datePublished":"2015-11-03T07:39:47+00:00","dateModified":"2018-07-31T11:02:55+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"description":"Un aborto spontaneo pu\u00f2 creare una forma unica di dolore che \u00e8 molto, molto difficile da superare. Una gravidanza pericolosa.","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#primaryimage","url":"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg","contentUrl":"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2015\/11\/mother-and-baby.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/03\/saro-riunita-ad-un-figlio-che-ho-abortito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Sar\u00f2 Riunita ad un Figlio che ho Abortito?"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9","name":"collaboratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","caption":"collaboratore"},"description":"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/collaboratore\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=3063"}],"version-history":[{"count":5,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3063\/revisions"}],"predecessor-version":[{"id":4367,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3063\/revisions\/4367"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=3063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=3063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=3063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}