{"id":3663,"date":"2016-03-17T14:51:42","date_gmt":"2016-03-17T13:51:42","guid":{"rendered":"http:\/\/it.elds.org\/gesu-cristo-org\/?p=3663"},"modified":"2018-07-31T12:18:18","modified_gmt":"2018-07-31T10:18:18","slug":"tu-sei-della-casa-di-israele","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/","title":{"rendered":"Tu sei della casa di Israele. Che cosa significa per te?"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\"><a href=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg\" rel=\"attachment wp-att-3664\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3664 size-full\" title=\"Piramide dell'Egitto\" src=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg\" alt=\"egitto\" width=\"696\" height=\"398\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg 696w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398-300x172.jpg 300w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/span><span class=\"s1\">Durante il periodo che ho passato al Centro BYU di Gerusalemme, il mio gruppo ha trascorso una settimana in Egitto e nella terra di Israele. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ero eccitata all&#8217;idea di vedere le piramidi, cavalcare un cammello, visitare i bazar e godere di una nuova parte del mondo, ma non ho pensato molto al significato spirituale dell&#8217;Egitto.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Fino a quando siamo arrivati l\u00ec e il nostro professore del vicino Oriente ci ha detto: &#8220;Benvenuti a casa!&#8221;<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Questo \u00e8 stato davvero uno strano modo di dare il benvenuto a qualcuno, in un posto in cui non \u00e8 mai stato prima, ma la sua spiegazione ha cambiato la mia prospettiva di tutta la nostra settimana e di tutto il mio <a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/11\/24\/sono-vere-le-storie-nella-bibbia\/\" target=\"_blank\" rel=\"noopener\">studio della Bibbia<\/a>, in particolare degli scritti di Isaia.<\/span><\/p>\n<blockquote>\n<p class=\"p1\"><span class=\"s1\">&#8220;Questa \u00e8 la vostra patria ancestrale. Il vostro bis-bis-bis-bis-bis-bis-bis-bis-bis-bisnonno Abramo \u00e8 stato qui, con Sara (e, in quel momento, le piramidi avevano gi\u00e0 800 anni!). <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Il suo pronipote Giuseppe fu venduto in schiavit\u00f9 qui e divenne un importante aiuto del faraone. i fratelli di Giuseppe furono salvati dalla fame, qui. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Tutta la casa d&#8217;Israele, ha vissuto qui per 400 anni, prima che Mos\u00e8 li portasse alla libert\u00e0. Quindi, benvenuti a casa.&#8221;<\/span><\/p>\n<\/blockquote>\n<h2><span class=\"s1\"><b>Tu sei della casa d&#8217;Israele<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Ho sempre amato e ammirato i patriarchi e i profeti, ma non li avevo mai realmente considerati come la mia famiglia.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Nello studiare il lavoro dei diversi studiosi ebrei, ho imparato che quando gli ebrei leggono la Torah la leggono come una storia di famiglia. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">E non \u00e8 solo un resoconto dei rapporti di Dio con il suo popolo antico; si tratta di un promemoria dei rapporti di Dio con la loro gente. E&#8217; la loro storia, le loro alleanze, il loro Dio.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Mentre Giacobbe si preparava a leggere gli insegnamenti di Isaia al popolo nefita, diceva loro: &#8220;Essi possono essere paragonati a voi, perch\u00e8 Voi siete della casa d&#8217;Israele.&#8221;<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Queste parole sono altrettanto vere per ciascuno di noi. Per nascita o adozione, ogni membro della Chiesa di Ges\u00f9 Cristo \u00e8 completamente un membro della casa di Israele. TU sei della casa, o della famiglia, di Israele.<\/span><\/p>\n<h2><span class=\"s1\"><b>Che cosa significa per te?<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\"><a href=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/abraham-praying-grant-clawson-1476027-gallery.jpg\" rel=\"attachment wp-att-3665\"><img decoding=\"async\" class=\"aligncenter wp-image-3665\" title=\"Abramo il padre di Israele\" src=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/abraham-praying-grant-clawson-1476027-gallery.jpg\" alt=\"Abramo\" width=\"600\" height=\"497\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/abraham-praying-grant-clawson-1476027-gallery.jpg 540w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/abraham-praying-grant-clawson-1476027-gallery-300x248.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">La conoscenza del luogo da cui sei venuto, dei cambiamenti, dice molto su chi sei e su chi vuoi essere. \u00c8 per questo che un nome \u00e8 cos\u00ec importante, perch\u00e9 prendere il nome di Ges\u00f9 Cristo \u00e8 cos\u00ec significativo. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Non ti identifichi anche con il nome di Israele? Ti consideri un membro della famiglia di Israele?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Studiando la storia familiare, spesso trovo caratteristiche ed interessi che condivido con i miei antenati. Un mio bisnonno era un matematico di talento. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Una bisnonna amava fischiare e scrivere poesie. Un nonno era un insegnante. Innumerevoli antenati hanno vissuto e amato il Vangelo.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Credo che queste cose non siano semplicemente una coincidenza. Siano esse da coltivare o siano naturali, le caratteristiche passano attraverso le linee della famiglia.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ora, quando ho letto nelle Scritture i racconti della mia famiglia, ho iniziato a cercare i tratti comuni e ad emulare le caratteristiche di Israele. Le ho lette come la mia storia, le mie promesse, il mio Dio.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Quando ho letto gli insegnamenti di Isaia, diretti al popolo dell&#8217;alleanza di Dio, Israele, li ho letti come se fossero insegnamenti per <i>me<\/i>.<\/span><\/p>\n<h2><span class=\"s1\"><b>Come farete a vivere come parte della famiglia di Israele?<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Mi piace pormi domande e scrivere, quando leggo le Scritture. In un\u2019attivit\u00e0 particolarmente significativa, mi sono posta le seguenti domande:<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Come faccio a sapere che io appartengo alla casa di Israele? Percepisco lo stesso senso e la stessa fiducia in queste promesse, cos\u00ec profondamente come fanno gli ebrei? Sostengo tale identit\u00e0? Come sarebbe la mia vita, se lo facessi?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ho pensato a tutte le cose che ho imparato dal fedele popolo ebraico, agli esempi tratti dalle Scritture e ho potuto stilare la seguente lista. Vorrei\u2026<\/span><\/p>\n<ul>\n<li class=\"li1\"><span class=\"s1\">contemplare di pi\u00f9 le alleanze del <a href=\"https:\/\/www.lds.org\/topics\/temples?lang=ita\" target=\"_blank\" rel=\"nofollow noopener\">tempio<\/a><\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">avere maggiore senso dei rituali, durante i quali mettere abiti religiosi<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">comunicare di pi\u00f9 con Dio, per tutta la giornata<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">conoscere meglio le Scritture<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">essere pi\u00f9 concentrata sul mio dovere in famiglia<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">osservare il giorno del sabato pi\u00f9 diligentemente<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">contare sulle storie delle Scritture che mi guidano e mi portano forza<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">vivere con fede totale e senza preoccupazioni mondane<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">vivere completamente la mia religione, senza preoccuparmi di ci\u00f2 che pensano gli altri<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\">Ho, poi, continuato con le seguenti domande: che cosa significa far parte del popolo dell&#8217;alleanza di Dio? Quali sono le Sue promesse?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">E infine: come posso pensare, sentire e agire se so di essere la figlia dell\u2019alleanza di Dio?<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Riflettere su queste domande, ha cambiato il modo in cui vedo le scritture e la storia del Suo popolo, il mio popolo, il mio Dio. Ha cambiato il mio modo di vedere le promesse di Dio.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">&#8220;Egli ci benedir\u00e0; Egli benedir\u00e0 la casa d&#8217;Israele&#8221;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il casato d&#8217;Israele \u00e8 il popolo dell&#8217;alleanza di Dio. Questa \u00e8 la nostra patria ancestrale, tutti noi siamo discendenti di Abramo.<\/p>\n","protected":false},"author":46,"featured_media":3664,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[488],"class_list":["post-3663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scritture","tag-racconti-biblici"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tu sei della Casa di Israele. Che cosa significa per te ed i tuoi figli?<\/title>\n<meta name=\"description\" content=\"Il casato d&#039;Israele \u00e8 il popolo dell&#039;alleanza di Dio. Questa \u00e8 la nostra patria ancestrale, tutti noi siamo discendenti di Abramo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tu sei della Casa di Israele. Che cosa significa per te ed i tuoi figli?\" \/>\n<meta property=\"og:description\" content=\"Il casato d&#039;Israele \u00e8 il popolo dell&#039;alleanza di Dio. Questa \u00e8 la nostra patria ancestrale, tutti noi siamo discendenti di Abramo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-17T13:51:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-31T10:18:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"398\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"collaboratore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"collaboratore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/\"},\"author\":{\"name\":\"collaboratore\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"headline\":\"Tu sei della casa di Israele. Che cosa significa per te?\",\"datePublished\":\"2016-03-17T13:51:42+00:00\",\"dateModified\":\"2018-07-31T10:18:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/\"},\"wordCount\":804,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/03\\\/israel-696x398.jpg\",\"keywords\":[\"racconti biblici\"],\"articleSection\":[\"Le Scritture\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/\",\"name\":\"Tu sei della Casa di Israele. Che cosa significa per te ed i tuoi figli?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/03\\\/israel-696x398.jpg\",\"datePublished\":\"2016-03-17T13:51:42+00:00\",\"dateModified\":\"2018-07-31T10:18:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\"},\"description\":\"Il casato d'Israele \u00e8 il popolo dell'alleanza di Dio. Questa \u00e8 la nostra patria ancestrale, tutti noi siamo discendenti di Abramo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/03\\\/israel-696x398.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/03\\\/israel-696x398.jpg\",\"width\":696,\"height\":398,\"caption\":\"Israele\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/03\\\/17\\\/tu-sei-della-casa-di-israele\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tu sei della casa di Israele. Che cosa significa per te?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/9f9faa532ad696ec68671c3e957b6ce9\",\"name\":\"collaboratore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g\",\"caption\":\"collaboratore\"},\"description\":\"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/collaboratore\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tu sei della Casa di Israele. Che cosa significa per te ed i tuoi figli?","description":"Il casato d'Israele \u00e8 il popolo dell'alleanza di Dio. Questa \u00e8 la nostra patria ancestrale, tutti noi siamo discendenti di Abramo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/","og_locale":"it_IT","og_type":"article","og_title":"Tu sei della Casa di Israele. Che cosa significa per te ed i tuoi figli?","og_description":"Il casato d'Israele \u00e8 il popolo dell'alleanza di Dio. Questa \u00e8 la nostra patria ancestrale, tutti noi siamo discendenti di Abramo","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/","og_site_name":"gesucristo.org","article_published_time":"2016-03-17T13:51:42+00:00","article_modified_time":"2018-07-31T10:18:18+00:00","og_image":[{"width":696,"height":398,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg","type":"image\/jpeg"}],"author":"collaboratore","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"collaboratore","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/"},"author":{"name":"collaboratore","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"headline":"Tu sei della casa di Israele. Che cosa significa per te?","datePublished":"2016-03-17T13:51:42+00:00","dateModified":"2018-07-31T10:18:18+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/"},"wordCount":804,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg","keywords":["racconti biblici"],"articleSection":["Le Scritture"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/","name":"Tu sei della Casa di Israele. Che cosa significa per te ed i tuoi figli?","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg","datePublished":"2016-03-17T13:51:42+00:00","dateModified":"2018-07-31T10:18:18+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9"},"description":"Il casato d'Israele \u00e8 il popolo dell'alleanza di Dio. Questa \u00e8 la nostra patria ancestrale, tutti noi siamo discendenti di Abramo","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/03\/israel-696x398.jpg","width":696,"height":398,"caption":"Israele"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/03\/17\/tu-sei-della-casa-di-israele\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Tu sei della casa di Israele. Che cosa significa per te?"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/9f9faa532ad696ec68671c3e957b6ce9","name":"collaboratore","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68ea6b338e1482bc760fb2dde30ab4a53d2b8af708975f664a091b0208c05535?s=96&d=mm&r=g","caption":"collaboratore"},"description":"Pi\u00f9fede.it ha lo scopo di fornire informazioni corrette ed edificanti sulla Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi Giorni. Non \u00e8 un sito internet ufficiale della Chiesa, n\u00e9 rappresenta necessariamente la posizione della Chiesa. Il sito internet \u00e8 gestito da comuni membri della Chiesa che vogliono condividere con gli altri il bene che deriva dal Vangelo restaurato di Ges\u00f9 Cristo. Questo articolo \u00e8 stato scritto o tradotto da uno dei nostri volontari. Se siete interessati a contribuire con i vostri testi (oppure video, grafica ecc), per favore contattaci.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/collaboratore\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=3663"}],"version-history":[{"count":6,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3663\/revisions"}],"predecessor-version":[{"id":6573,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3663\/revisions\/6573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/3664"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=3663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=3663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=3663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}