{"id":3926,"date":"2016-05-26T14:40:18","date_gmt":"2016-05-26T12:40:18","guid":{"rendered":"http:\/\/it.elds.org\/gesu-cristo-org\/?p=3926"},"modified":"2018-07-30T16:58:54","modified_gmt":"2018-07-30T14:58:54","slug":"avete-decisione-prendere","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/","title":{"rendered":"Avete una decisione da prendere? Esercitate la fede!"},"content":{"rendered":"<h2><span class=\"s1\"><b><a href=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3927 size-full\" title=\"Decisione da prendere\" src=\"http:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg\" alt=\"decisioni\" width=\"795\" height=\"497\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg 795w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280-300x188.jpg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280-768x480.jpg 768w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280-400x250.jpg 400w\" sizes=\"(max-width: 795px) 100vw, 795px\" \/><\/a><\/b><\/span><\/h2>\n<h2><span class=\"s1\"><b>Decisione da Prendere<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Due anni fa, la pi\u00f9 giovane dei miei figli stava cercando di scegliere un\u2019universit\u00e0. Era chiaro il suo corso di studi ed era stata presa in entrambe le migliori scuole che aveva scelto. Ma dal momento che, entrambe, erano scuole importanti, non riusciva<\/span><span class=\"s1\">&nbsp;a decidere<\/span><span class=\"s1\"> una decisione a quale iscriversi.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Dovevo fare un viaggio d&#8217;affari nella citt\u00e0 in cui si trovava una delle sue universit\u00e0 &#8220;finaliste&#8221;, cos\u00ec l&#8217;ho invitata a venire con me e visitare la scuola, mentre partecipavo alle riunioni. Ha trascorso ore, in quel giorno, a parlare con i professori e a visitare le strutture e, quando siamo tornati insieme, quella sera, mi ha detto: &#8220;Mi \u00e8 piaciuta&#8221;.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Credendo che fosse giusto che misurasse entrambe le scuole in modo paritario, per\u00f2, mia moglie ed io l\u2019abbiamo incoraggiata, a nostre spese, a visitare la seconda scuola. Dopo una giornata simile, passata visitando le facolt\u00e0 e le strutture di quella seconda scuola, ci ha chiamato al telefono. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Con entrambe le esperienze fresche nella mente, ci ha detto, con una punta di timore nella sua voce, che questo secondo programma era, in effetti, &#8220;il programma dei suoi sogni&#8221;. Perfetto, in ogni modo possibile. Quindi immaginate la nostra sorpresa quando ci ha detto che non era sicura su quale scuola scegliere.<\/span><\/p>\n<h2><span class=\"s1\"><b>Decisioni che cambiano il corso della vita<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Il leader religioso americano <a href=\"https:\/\/www.lds.org\/church\/leader\/thomas-s-monson?lang=ita\"><span class=\"s2\">Thomas S. Monson<\/span><\/a> ha detto: \u201cLa porta della storia gira su piccoli cardini e cos\u00ec fa la vita delle persone. Le scelte che facciamo, determinano il nostro destino&#8221;.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Mentre alcune decisioni sono grandi come chicchi di grano o di riso soffiato \u2013 metto le scarpe rosse o bianche?<span class=\"Apple-converted-space\">&nbsp; <\/span>&#8211; e hanno solo un impatto marginale sul nostro giorno o il nostro futuro, altre possono cambiare il corso della nostra vita. Tali decisioni sono quelle con le quali abbiamo potuto davvero usare un certo aiuto, anche l&#8217;aiuto divino, che dovrebbe essere a disposizione per noi.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Centinaia di milioni di persone testimoniano che tale aiuto \u00e8 stato, infatti, il loro modo di ricevere la luce, la direzione, la conoscenza e la chiarezza, ben oltre la loro normale capacit\u00e0 di ragionamento o di discernimento.<\/span><\/p>\n<h2><span class=\"s1\"><b>Piccoli passi per esercitare la fede<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Ma alcuni mini-passi precedono l\u2019essere in grado di fare grandi salti, e sono richiesti tramite l\u2019&#8221;esercizio&#8221; della nostra <a href=\"https:\/\/www.lds.org\/topics\/faith?lang=ita\"><span class=\"s2\">fede<\/span><\/a>:<\/span><\/p>\n<ul>\n<li class=\"li1\"><span class=\"s1\"><b>Respirare e riflettere in profondit\u00e0<\/b>: si tratta di una questione che si pu\u00f2 risolvere in modo chiaro, se ci riflettete per un pomeriggio? Avete gi\u00e0 affrontato con successo qualcosa di simile prima d&#8217;ora?<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\"><b>Equilibrio e allineamento<\/b>: come vi comportate per le cose che gi\u00e0 sapete essere nel giusto? O essere sbagliate?<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\"><b>Focus<\/b>: a volte, non vi \u00e8 una risposta sbagliata. C\u2019\u00e8 una buona risposta e una risposta migliore. Provate a focalizzarvi su dettagli precisi e, quindi, a trovare chiarezza.<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\"><b>Stretching<\/b>: potete guardare &#8220;in avanti&#8221; e vedere dove quello che una determinata decisione comporta? Proiettare i se\/quindi e ragionare in base ad essi \u00e8 una tecnica comune, nel processo decisionale di alto livello.<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\"><b>Indagare<\/b>: chiedete aiuto all\u2019esperienza e alla saggezza degli altri, di cui avete gi\u00e0 imparato a fidarvi, e chiedere il loro consiglio.<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\"><b>\u201cRestate in zona, quindi andate fuori strada\u201d<\/b>: impegnatevi in un momento di preghiera o di meditazione, in base alle vostre convinzioni, e non siate indecisi. Il filosofo americano e autore Henry David Thoreau ha scritto che &#8220;L&#8217;umilt\u00e0, come l&#8217;oscurit\u00e0, rivela le luci celesti&#8221;. Dobbiamo veramente aprirci alle potenziali risposte che provengono da quello che va oltre la nostra esperienza limitata.<\/span><\/li>\n<li class=\"li1\"><span class=\"s1\">Infine, utilizzate un &#8216;<b>video del cuore&#8217;<\/b>: &#8220;Nella meditazione, andate in profondit\u00e0 nel cuore&#8221; afferma il Tao Te Ching. La Preghiera del Signore, nel <a href=\"https:\/\/www.lds.org\/topics\/new-testament?lang=ita\"><span class=\"s2\">Nuovo Testamento<\/span><\/a>, insegna: &#8220;Quando preghi, entra nella tua cameretta&#8221;. Quest&#8217;ultimo termine, nella lingua originale aramaica, pu\u00f2 essere meglio reso con le parole &#8220;stanza segreta&#8221; della propria <a href=\"https:\/\/www.lds.org\/topics\/soul?lang=ita\"><span class=\"s2\">anima<\/span><\/a>.<\/span><\/li>\n<\/ul>\n<h2><span class=\"s1\"><b>E la risposta arriva<\/b><\/span><\/h2>\n<p class=\"p1\"><span class=\"s1\">Molti autori orientati verso la fede hanno notato che &#8220;la rivelazione \u00e8 sparsa&#8221; in tutto il nostro mondo personale, nelle lezioni private di un <a href=\"https:\/\/www.lds.org\/topics\/god-the-father?lang=ita\"><span class=\"s2\">Dio<\/span><\/a> che si prende cura di noi. Ci\u00f2 che emerge, come la saggezza che arriva tramite l\u2019esercizio precedente, se viene fedelmente eseguito, pu\u00f2 essere attendibile come risposta migliore.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Per quanto riguarda mia figlia, la potenza accumulata tramite la sua esperienza precedente ed i suoi sforzi presenti, ha portato ad una chiarezza che, semplicemente, prima non c&#8217;era. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Dopo aver studiato, parlato con molti, riflettendo profondamente e proiettando interiormente ci\u00f2 che ogni scelta le avrebbe portato, ha guardato nel profondo del suo cuore e, poi, si \u00e8 messa in ginocchio. E la risposta \u00e8 arrivata.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\"><i>Questo articolo \u00e8 stato scritto da Coke Newell e pubblicato sul sito <\/i><span class=\"s2\"><i><a href=\"http:\/\/faithcounts.com\/got-decision-make-exercise-faith\/\" rel=\"nofollow\">faithcounts.org<\/a>&nbsp;e<\/i><\/span><i>&nbsp;tradotto da Cinzia Galasso.<\/i><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decisione da Prendere Due anni fa, la pi\u00f9 giovane dei miei figli stava cercando di scegliere un\u2019universit\u00e0. Era chiaro il suo corso di studi ed era stata presa in entrambe le migliori scuole che aveva scelto. Ma dal momento che, entrambe, erano scuole importanti, non riusciva&nbsp;a decidere una decisione a quale iscriversi. Dovevo fare un [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":3927,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[416],"tags":[972],"class_list":["post-3926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fede","tag-vita-cristiana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avete una decisione da prendere? Esercitate la fede!<\/title>\n<meta name=\"description\" content=\"Quando abbiamo una decisione da prendere, la strada migliore \u00e8 chiedere un aiuto divino, dopo aver esercitato la fede, tramite piccoli e semplici passi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avete una decisione da prendere? Esercitate la fede!\" \/>\n<meta property=\"og:description\" content=\"Quando abbiamo una decisione da prendere, la strada migliore \u00e8 chiedere un aiuto divino, dopo aver esercitato la fede, tramite piccoli e semplici passi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-26T12:40:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-30T14:58:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"795\" \/>\n\t<meta property=\"og:image:height\" content=\"497\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cinzia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cinzia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/\"},\"author\":{\"name\":\"Cinzia\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/ce134334ee9829422fabc907058b43bd\"},\"headline\":\"Avete una decisione da prendere? Esercitate la fede!\",\"datePublished\":\"2016-05-26T12:40:18+00:00\",\"dateModified\":\"2018-07-30T14:58:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/\"},\"wordCount\":780,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/05\\\/sky-967964_1280.jpg\",\"keywords\":[\"vita cristiana\"],\"articleSection\":[\"Fede\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/\",\"name\":\"Avete una decisione da prendere? Esercitate la fede!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/05\\\/sky-967964_1280.jpg\",\"datePublished\":\"2016-05-26T12:40:18+00:00\",\"dateModified\":\"2018-07-30T14:58:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/ce134334ee9829422fabc907058b43bd\"},\"description\":\"Quando abbiamo una decisione da prendere, la strada migliore \u00e8 chiedere un aiuto divino, dopo aver esercitato la fede, tramite piccoli e semplici passi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/05\\\/sky-967964_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2016\\\/05\\\/sky-967964_1280.jpg\",\"width\":795,\"height\":497},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2016\\\/05\\\/26\\\/avete-decisione-prendere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avete una decisione da prendere? Esercitate la fede!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/ce134334ee9829422fabc907058b43bd\",\"name\":\"Cinzia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g\",\"caption\":\"Cinzia\"},\"description\":\"Cinzia \u00e8 un'impiegata ed una traduttrice. Ha una laurea in Scienze dell'Educazione e ha anche insegnato, per un paio di anni, a bambini della scuola materna, un lavoro che ha amato molto. E' stata un'insegnante nelle classi della Societ\u00e0 di Soccorso, delle Giovani Donne e dell'Istituto. Ha molti interessi: patchwork, quilling, oli essenziali. Le piace prendersi cura di s\u00e8 con soluzioni naturali. E' vegana e ama gli animali e la natura ed \u00e8 fermamente convinta che le creazioni di Dio siano sacre. E' una volontaria dell'ENPA, un'associazione italiana, per la protezione degli animali ed \u00e8 anche un membro di Greenpeace e del WWF. Ama passare il tempo con la sua famiglia e i suoi amici. Ama il vangelo di Ges\u00f9 Cristo e sa che le famiglie sono eterne.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/cinzia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avete una decisione da prendere? Esercitate la fede!","description":"Quando abbiamo una decisione da prendere, la strada migliore \u00e8 chiedere un aiuto divino, dopo aver esercitato la fede, tramite piccoli e semplici passi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/","og_locale":"it_IT","og_type":"article","og_title":"Avete una decisione da prendere? Esercitate la fede!","og_description":"Quando abbiamo una decisione da prendere, la strada migliore \u00e8 chiedere un aiuto divino, dopo aver esercitato la fede, tramite piccoli e semplici passi.","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/","og_site_name":"gesucristo.org","article_published_time":"2016-05-26T12:40:18+00:00","article_modified_time":"2018-07-30T14:58:54+00:00","og_image":[{"width":795,"height":497,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg","type":"image\/jpeg"}],"author":"Cinzia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Cinzia","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/"},"author":{"name":"Cinzia","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/ce134334ee9829422fabc907058b43bd"},"headline":"Avete una decisione da prendere? Esercitate la fede!","datePublished":"2016-05-26T12:40:18+00:00","dateModified":"2018-07-30T14:58:54+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/"},"wordCount":780,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg","keywords":["vita cristiana"],"articleSection":["Fede"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/","name":"Avete una decisione da prendere? Esercitate la fede!","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg","datePublished":"2016-05-26T12:40:18+00:00","dateModified":"2018-07-30T14:58:54+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/ce134334ee9829422fabc907058b43bd"},"description":"Quando abbiamo una decisione da prendere, la strada migliore \u00e8 chiedere un aiuto divino, dopo aver esercitato la fede, tramite piccoli e semplici passi.","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/05\/sky-967964_1280.jpg","width":795,"height":497},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2016\/05\/26\/avete-decisione-prendere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Avete una decisione da prendere? Esercitate la fede!"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/ce134334ee9829422fabc907058b43bd","name":"Cinzia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g","caption":"Cinzia"},"description":"Cinzia \u00e8 un'impiegata ed una traduttrice. Ha una laurea in Scienze dell'Educazione e ha anche insegnato, per un paio di anni, a bambini della scuola materna, un lavoro che ha amato molto. E' stata un'insegnante nelle classi della Societ\u00e0 di Soccorso, delle Giovani Donne e dell'Istituto. Ha molti interessi: patchwork, quilling, oli essenziali. Le piace prendersi cura di s\u00e8 con soluzioni naturali. E' vegana e ama gli animali e la natura ed \u00e8 fermamente convinta che le creazioni di Dio siano sacre. E' una volontaria dell'ENPA, un'associazione italiana, per la protezione degli animali ed \u00e8 anche un membro di Greenpeace e del WWF. Ama passare il tempo con la sua famiglia e i suoi amici. Ama il vangelo di Ges\u00f9 Cristo e sa che le famiglie sono eterne.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/cinzia\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=3926"}],"version-history":[{"count":3,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3926\/revisions"}],"predecessor-version":[{"id":5409,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/3926\/revisions\/5409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/3927"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=3926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=3926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=3926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}