{"id":5227,"date":"2017-06-11T20:46:33","date_gmt":"2017-06-11T18:46:33","guid":{"rendered":"https:\/\/it.elds.org\/gesu-cristo-org\/?p=5227"},"modified":"2017-11-28T11:55:55","modified_gmt":"2017-11-28T10:55:55","slug":"gesu-nostro-leader","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/","title":{"rendered":"Ges\u00f9 Cristo: il nostro miglior leader"},"content":{"rendered":"<p><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-5229 size-full\" title=\"gesu-nostro-leader\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg\" alt=\"gesu-nostro-leader\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader-300x172.jpg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader-768x439.jpg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a><\/p>\n<p>Cosa significa essere un leader? Il termine leader deriva dall\u2019inglese to lead che significa dirigere, guidare. L\u2019etimologia ci fa subito comprendere che il leader guida un gruppo di persone, i quali fanno costante riferimento a lui.<\/p>\n<p>Molti non lo sanno, ma contrariamente a ci\u00f2 che si pensa, i due concetti di essere un leader ed essere un seguace, sono tra loro molto pi\u00f9 connessi &nbsp;di quello che si possa pensare.<\/p>\n<p>Infatti, ogni grande leader prima di divenire tale \u00e8 stato un seguace &nbsp;e, per questa ragione, ha avuto, o ha, un grande maestro sempre al suo fianco. Cerchiamo di capire meglio cosa significa.<\/p>\n<h2>Essere leader o seguaci?<\/h2>\n<p>Non appena mi laureai mi misi immediatamente, come tutti i giovani della mia et\u00e0, alla ricerca di un lavoro.<\/p>\n<p>Purtroppo per\u00f2 non fu cos\u00ec semplice e, di conseguenza, iniziai a dover affrontare la dura e triste realt\u00e0 che da quasi dieci anni stanno attraversando sia l&#8217;Italia che il resto dei paesi europei, ovvero il fenomeno della disoccupazione.<\/p>\n<p>Con il passare del tempo, e grazie ad un po&#8217; di determinazione e caparbiet\u00e0, ebbi la possibilit\u00e0 di fare un colloquio conoscitivo presso un&#8217;agenzia di viaggi abbastanza nota nella mia citt\u00e0.<\/p>\n<p>Mi venne proposto non un&#8217;assunzione ma bens\u00ec un tirocinio formativo in qualit\u00e0 di addetto Front Office della biglietteria, e che sarei stato affiancato per il primo periodo da un tutor incaricato alla mia crescita aziendale.<\/p>\n<p>Anche se non avevo nessuna esperienza circa il mondo dei viaggi non avendo neanche viaggiato molto nella mia vita, decisi di accettare.<\/p>\n<p>Terminato il colloquio tornai a casa molto felice, al punto che non vedevo l&#8217;ora di iniziare questa mia nuova esperienza. Ero sicuro che mi sarei fatto notare immediatamente per il mio talento e la mia voglia di fare.<\/p>\n<h2>Ricordo ancora il mio primo giorno<\/h2>\n<p>Ero talmente spaventato che per poco non me ne stavo per scappare via dal posto di lavoro. Molti non sanno che l&#8217;addetto Front Office di un&#8217;agenzia viaggi non \u00e8 soltanto una figura incaricata ad emettere semplicemente i biglietti che gli vengono richiesti.<\/p>\n<p>Oltre a questo deve essere in grado di rispondere efficacemente e celermente, grazie alla sua conoscenza ed esperienza, a tutte le richieste e &nbsp;che gli vengono fatte dalla clientela sapendola consigliare sulla scelta pi\u00f9 opportuna e, in altre parole, deve essere un riferimento per il viaggiatore e deve saper rappresentare &nbsp;nel migliore dei modi l&#8217;azienda.<\/p>\n<p>A lui \u00e8 affidato il difficile compito &nbsp;della &#8220;customer care&#8221; e della &#8220;customer satisfaction&#8221;. Non lo sapevo, fino a quel giorno.<\/p>\n<p>Per la gran parte delle aziende il luned\u00ec rappresenta un giorno molto faticoso in quanto la maggior parte dei clienti si presentano quel giorno.<\/p>\n<p>Anche quel luned\u00ec, a conferma della regola, in agenzia si presentarono molti clienti ognuno dei quali con una richiesta &nbsp;diversa e molto specifica.<\/p>\n<p>Entrando in agenzia erano costretti &nbsp;ad interagire immediatamente con me, addetto al front office, vedendo nella mia persona colui che li avrebbe potuti e dovuti aiutare nelle loro richieste.<\/p>\n<p>Mi trovai a dover affrontare una situazione ben pi\u00f9 grande di me. Infatti, sebbene avessi tanta buona volont\u00e0 non avevo nessuna conoscenza n\u00e9 sul mestiere e n\u00e9 tanto meno circa il come comportarsi con la clientela soprattutto con quella poco cortese.<\/p>\n<p>Avrei potuto dire tranquillamente che ero un tirocinante al suo primo giorno.<\/p>\n<p>Ma essendo di base una persona timida ed un po&#8217; ansiosa, a causa della situazione, entrai subito nel panico al punto che mi sembrava di non riuscire pi\u00f9 a poter parlare scatenando il malcontento dei clienti.<\/p>\n<p>Per fortuna il mio tutor si accorse della situazione che si era venuta a creare e, immediatamente, intervenne in mio soccorso spiegando che ero un tirocinante al suo primo giorno e riuscendo cos\u00ec sia ad aiutarmi che a rispondere alle esigenze dell&#8217;utenza.<\/p>\n<p>Al termine della giornata lavorativa il mio tutor si avvicin\u00f2 a me per parlarmi.<\/p>\n<p>Pensavo che mi avrebbe rimproverato perch\u00e9 non ero stato in grado di svolgere il mio compito. Invece disse che era felice che la giornata era finalmente finita poich\u00e9 sebbene sia bello stare a contatto con il pubblico, alle volte \u00e8 molto difficile riuscire ad essere cortesi e disponibili con alcune persone, ma non impossibile.<\/p>\n<p>Dopo aver detto, questo mi chiese se avevo voglia di imparare di pi\u00f9 circa il modo in cui lavorano le agenzie di viaggi in generale e, in particolare, un addetto Front office in modo tale da non entrare pi\u00f9 nel panico.<\/p>\n<p>Ovviamente gli risposi di si e quando gli chiesi da dove avrei dovuto iniziare mi rispose che avrei dovuto inizialmente seguirlo costantemente durante il lavoro in modo tale da poter acquisire le &nbsp;giuste competenze e svilupparle unitamente al mio modo di essere. &nbsp;<\/p>\n<p>Grazie a questo periodo di affiancamento riuscii a scoprire una serie di tecniche e modi di fare che mi permisero di crescere sia professionalmente che caratterialmente.<\/p>\n<h2>Ognuno ha bisogno di un leader<\/h2>\n<p>Lo seguivo costantemente in tutto. Per la sua bravura e la sua pazienza era diventato un vero e proprio esempio da seguire, un vero leader.<\/p>\n<p>Un luned\u00ec si presentarono come di consueto molte persone e lui decise di lasciar gestire a me tutte quelle persone.<\/p>\n<p>Sebbene gli risposi che non mi sentivo all&#8217;altezza, lui mi disse che invece ero pronto in quanto mi sarebbe bastato ripeter ci\u00f2 che gli avevo visto fare durante il periodo di affiancamento senza mai dimenticare la mia personalit\u00e0.<\/p>\n<p>Ci volli provare e come avevo visto fare molte volte chiesi, cliente dopo cliente, quali fossero le necessit\u00e0 illustrando caso per caso quali erano le soluzioni pi\u00f9 congeniali che avevamo per loro.<\/p>\n<p>Il tutto tenendo conto della mia timidezza e quindi con i miei giusti tempi. Ero riuscito in ci\u00f2 che tempo prima mi era sembrato impossibile. Ero molto felice e molto grato al mio mentore. Non ci sarei riuscito se non fosse stato per lui.<\/p>\n<p>Al termine del lavoro, lo ringraziai per la fiducia e la pazienza che aveva avuto nei miei confronti.<\/p>\n<p>Dal canto suo disse che non aveva fatto nulla di eccezionale ma che ero riuscito, grazie alla mia voglia di fare e di imparare, ad apprendere tutto quello che c&#8217;era da apprendere.<\/p>\n<p>Vedendo quanto ero migliorato, qualche tempo dopo mi volle affidare la formazione di un nuovo tirocinante da poco arrivato.<\/p>\n<p>Per assolvere al meglio a questo compito decisi di immedesimarmi nel nuovo arrivato, o meglio che fossi io a dover imparare e quindi mi sforzai ad essere il pi\u00f9 chiaro e semplice possibile verso di lui.<\/p>\n<p>Riuscii grazie a questo mio modo di fare ad ottenere grandi risultati. Ero riuscito ad &nbsp;essere un buon riferimento pensando ancora di essere un seguace.<\/p>\n<p>Grazie al mio mentore e alla sua fiducia nei miei confronti avevo appreso qualcosa di estremamente importante: &#8221;per essere degli ottimi leader bisogna continuamente essere degli <a href=\"https:\/\/mormoni.com\/le-scritture\/gesu-cristo-nel-nuovo-testamento\/\">umili discepoli<\/a>&#8221;.<\/p>\n<h2>Il Nostro Miglior Leader e Miglior Seguace: Ges\u00f9 Cristo<\/h2>\n<p>A tal proposito, molto interessanti sono le parole dette durante una Conferenza Generale dal Presidente dei Giovani Uomini:<\/p>\n<blockquote><p>&#8220;[&#8230;]Se vi chiedessi: \u201cChi \u00e8 il dirigente migliore che sia mai esistito?\u201d, cosa mi rispondereste? La risposta, ovviamente, \u00e8: \u201cGes\u00f9 Cristo\u201d. Egli ha incarnato l\u2019esempio perfetto di ogni qualit\u00e0 che si possa immaginare in un dirigente.<\/p>\n<p>Ma se vi chiedessi: \u201cChi \u00e8 il seguace migliore che sia mai esistito?\u201d, la risposta non sarebbe forse ancora: \u201cGes\u00f9 Cristo\u201d? Egli \u00e8 il dirigente migliore perch\u00e9 \u00e8 il migliore seguace: segue il Padre Suo in modo perfetto, in tutte le cose.&#8221; (<a href=\"http:\/\/www.lds.org\/general-conference\/2016\/04\/the-greatest-leaders-are-the-greatest-followers?lang=ita\">Conferenza Generale Aprile 2016, Presidente Stephen W. Owen &#8220;I dirigenti migliori sono i seguaci migliori&#8221;<\/a>).<\/p><\/blockquote>\n<p>Egli \u00e8 l&#8217;esempio di miglior dirigente e miglior seguace allo stesso tempo. Ges\u00f9 Cristo \u00e8 venuto sulla terra proprio per essere per noi la giusta guida per la nostra salvezza. Sicuramente aveva pi\u00f9 di qualche paura nel fare questo.<\/p>\n<p>Ma il Suo mentore, il Padre Celeste, aveva fiducia in Lui per via della Sua umilt\u00e0 nell&#8217;essere un seguace.<\/p>\n<p>La stessa umilt\u00e0 l&#8217;ha voluta trasmettere a noi per essere persone migliori mediante il suo operato come dirigente della Sua Chiesa qui sulla terra per affrontare le difficolt\u00e0.<\/p>\n<p>Sicuramente ci saranno dei momenti in cui la strada davanti a noi sembrer\u00e0 buia e non sapremo che cosa dover fare.<\/p>\n<p>Ma se saremo degli ottimi seguaci avendo sempre come riferimento il nostro mentore, <a href=\"https:\/\/mormoni.com\/credenze\/gesu-cristo\/nuove-scoperte-gesu-di-nazareth\/\">Ges\u00f9 Cristo<\/a>, e il suo esempio di umilt\u00e0, saremo in grado di affrontare non solo le nostre difficolt\u00e0, ma potremo trasmettere il nostro esempio alle persone a noi vicine in modo che anch&#8217;esse facciano lo stesso avendo noi come riferimento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ges\u00f9 Cristo: il nostro miglior leader. Non dimentichiamoci mai di seguire il nostro leader: Ges\u00f9 Cristo<\/p>\n","protected":false},"author":49,"featured_media":5229,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[562],"class_list":["post-5227","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dottrine","tag-vangelo-di-gesu-cristo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ges\u00f9 Cristo: il nostro miglior leader | gesucristo.org<\/title>\n<meta name=\"description\" content=\"Non dimentichiamoci mai di seguire il nostro leader: Ges\u00f9 Cristo. Il Padre Celeste, aveva fiducia in Lui per via della Sua umilt\u00e0 nell&#039;essere un seguace.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ges\u00f9 Cristo: il nostro miglior leader | gesucristo.org\" \/>\n<meta property=\"og:description\" content=\"Non dimentichiamoci mai di seguire il nostro leader: Ges\u00f9 Cristo. Il Padre Celeste, aveva fiducia in Lui per via della Sua umilt\u00e0 nell&#039;essere un seguace.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-11T18:46:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-28T10:55:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alberto Battista\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alberto Battista\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/\"},\"author\":{\"name\":\"Alberto Battista\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/be317120199caca8325ac4532dbfbf26\"},\"headline\":\"Ges\u00f9 Cristo: il nostro miglior leader\",\"datePublished\":\"2017-06-11T18:46:33+00:00\",\"dateModified\":\"2017-11-28T10:55:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/\"},\"wordCount\":1422,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2017\\\/06\\\/gesu-nostro-leader.jpg\",\"keywords\":[\"Vangelo di Ges\u00f9 Cristo\"],\"articleSection\":[\"Dottrine\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/\",\"name\":\"Ges\u00f9 Cristo: il nostro miglior leader | gesucristo.org\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2017\\\/06\\\/gesu-nostro-leader.jpg\",\"datePublished\":\"2017-06-11T18:46:33+00:00\",\"dateModified\":\"2017-11-28T10:55:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/be317120199caca8325ac4532dbfbf26\"},\"description\":\"Non dimentichiamoci mai di seguire il nostro leader: Ges\u00f9 Cristo. Il Padre Celeste, aveva fiducia in Lui per via della Sua umilt\u00e0 nell'essere un seguace.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2017\\\/06\\\/gesu-nostro-leader.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2017\\\/06\\\/gesu-nostro-leader.jpg\",\"width\":948,\"height\":542,\"caption\":\"gesu-nostro-leader\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2017\\\/06\\\/11\\\/gesu-nostro-leader\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ges\u00f9 Cristo: il nostro miglior leader\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/be317120199caca8325ac4532dbfbf26\",\"name\":\"Alberto Battista\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f197b257348568dfe9bb0026d0b9b474c31be908b3c82478f3cdcd6ab88689d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f197b257348568dfe9bb0026d0b9b474c31be908b3c82478f3cdcd6ab88689d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3f197b257348568dfe9bb0026d0b9b474c31be908b3c82478f3cdcd6ab88689d?s=96&d=mm&r=g\",\"caption\":\"Alberto Battista\"},\"description\":\"Alberto Battista \u00e8 un giovane mormone da poco laureato e, quando non \u00e8 impegnato nella ricerca di un lavoro ( quasi mai!), si dedica ad apprezzare le bellezze della vita prediligendo l'amore per gli animali e il body building. Ama molto i rapporti interpersonali e cerca di diffondere attraverso i suoi scritti la parola del Vangelo, che ritiene essere il '' bisturi '' per debellare il male che pervade la nostra societ\u00e0.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ges\u00f9 Cristo: il nostro miglior leader | gesucristo.org","description":"Non dimentichiamoci mai di seguire il nostro leader: Ges\u00f9 Cristo. Il Padre Celeste, aveva fiducia in Lui per via della Sua umilt\u00e0 nell'essere un seguace.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/","og_locale":"it_IT","og_type":"article","og_title":"Ges\u00f9 Cristo: il nostro miglior leader | gesucristo.org","og_description":"Non dimentichiamoci mai di seguire il nostro leader: Ges\u00f9 Cristo. Il Padre Celeste, aveva fiducia in Lui per via della Sua umilt\u00e0 nell'essere un seguace.","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/","og_site_name":"gesucristo.org","article_published_time":"2017-06-11T18:46:33+00:00","article_modified_time":"2017-11-28T10:55:55+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg","type":"image\/jpeg"}],"author":"Alberto Battista","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Alberto Battista","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/"},"author":{"name":"Alberto Battista","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/be317120199caca8325ac4532dbfbf26"},"headline":"Ges\u00f9 Cristo: il nostro miglior leader","datePublished":"2017-06-11T18:46:33+00:00","dateModified":"2017-11-28T10:55:55+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/"},"wordCount":1422,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg","keywords":["Vangelo di Ges\u00f9 Cristo"],"articleSection":["Dottrine"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/","name":"Ges\u00f9 Cristo: il nostro miglior leader | gesucristo.org","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg","datePublished":"2017-06-11T18:46:33+00:00","dateModified":"2017-11-28T10:55:55+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/be317120199caca8325ac4532dbfbf26"},"description":"Non dimentichiamoci mai di seguire il nostro leader: Ges\u00f9 Cristo. Il Padre Celeste, aveva fiducia in Lui per via della Sua umilt\u00e0 nell'essere un seguace.","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2017\/06\/gesu-nostro-leader.jpg","width":948,"height":542,"caption":"gesu-nostro-leader"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/06\/11\/gesu-nostro-leader\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Ges\u00f9 Cristo: il nostro miglior leader"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/be317120199caca8325ac4532dbfbf26","name":"Alberto Battista","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/3f197b257348568dfe9bb0026d0b9b474c31be908b3c82478f3cdcd6ab88689d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3f197b257348568dfe9bb0026d0b9b474c31be908b3c82478f3cdcd6ab88689d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3f197b257348568dfe9bb0026d0b9b474c31be908b3c82478f3cdcd6ab88689d?s=96&d=mm&r=g","caption":"Alberto Battista"},"description":"Alberto Battista \u00e8 un giovane mormone da poco laureato e, quando non \u00e8 impegnato nella ricerca di un lavoro ( quasi mai!), si dedica ad apprezzare le bellezze della vita prediligendo l'amore per gli animali e il body building. Ama molto i rapporti interpersonali e cerca di diffondere attraverso i suoi scritti la parola del Vangelo, che ritiene essere il '' bisturi '' per debellare il male che pervade la nostra societ\u00e0.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/5227","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=5227"}],"version-history":[{"count":6,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/5227\/revisions"}],"predecessor-version":[{"id":5234,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/5227\/revisions\/5234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/5229"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=5227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=5227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=5227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}