{"id":6240,"date":"2018-02-16T13:09:03","date_gmt":"2018-02-16T12:09:03","guid":{"rendered":"https:\/\/it.elds.org\/gesu-cristo-org\/?p=6240"},"modified":"2018-06-27T22:41:03","modified_gmt":"2018-06-27T20:41:03","slug":"trovare-la-pace-interiore","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/","title":{"rendered":"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-6241\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg\" alt=\"Trovare la pace interiore\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore-300x172.jpeg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore-768x439.jpeg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>Sii fermo: trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo attraverso la meditazione.&nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Spesso proviamo a rafforzarci spiritualmente con la preghiera quotidiana e la lettura delle scritture.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tuttavia, talvolta il nostro impegno per queste pratiche \u00e8 irregolare, nel migliore dei casi. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante la preghiera, \u00e8 naturale per le nostre menti vagare; quando leggiamo le Scritture, la nostra attenzione spesso si sposta su ci\u00f2 che faremo dopo. Non stupisce il fatto che sia facile sentirsi spiritualmente vuoti e apatici.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Di fronte a questi problemi, ho fatto un importante passo avanti quando ho iniziato a praticare l&#8217;arte della meditazione. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">I Santi degli Ultimi Giorni usano spesso la parola &#8220;meditare&#8221; per voler dire qualcosa come &#8220;ponderare&#8221;. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ma il tipo di meditazione che ho scoperto indica un approccio pi\u00f9 intenzionale per portare serenit\u00e0 e concentrazione alle nostre menti distratte. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">E\u2019 questo il significato dell\u2019insegnamento di pace interiore e di quiete a cui credo si riferisse il presidente McKay quando ha detto: <\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cLa meditazione \u00e8 la lingua dell&#8217;anima. . . [\u00c8] una delle porte pi\u00f9 segrete e pi\u00f9 sacre attraverso le quali arriviamo alla presenza del Signore\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La meditazione, tuttavia, non \u00e8 solo un&#8217;attivit\u00e0 mattutina di 10 minuti. Essa implica il vedere ed incontrare il mondo in modo completo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nella mia vita spirituale, ho trovato molte delle verit\u00e0 insegnate dai maestri della meditazione che hanno approfondito e arricchito la mia comprensione del Vangelo restaurato di Ges\u00f9 Cristo.<\/span><\/p>\n<h2>La nostra vera essenza<\/h2>\n<p><span style=\"font-weight: 400;\">Una delle idee centrali della filosofia della meditazione \u00e8 che al centro di ogni essere umano c&#8217;\u00e8 un&#8217;anima infinita. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nella tradizione Hindu, questa essenza \u00e8 chiamata &#8220;atman&#8221;. L&#8217;atman \u00e8 una specie di scintilla divina, una parte di Dio che abita nel corpo umano. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gli esseri umani stanno sperimentando un temporaneo senso di separazione da Dio, ma possono ricongiungersi a Lui nel ricordare la nostra vera natura di esseri divini.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Queste idee dovrebbero essere in sintonia con i Santi degli Ultimi Giorni che comprendono anche che siamo esseri eterni e che il nostro io pi\u00f9 vero e pi\u00f9 profondo deriva dalla stessa sostanza di Dio. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Impariamo che &#8220;l&#8217;uomo al principio era con Dio. L&#8217;intelligenza, o la luce della verit\u00e0, non fu creata o fatta, n\u00e9 pu\u00f2 esserlo. &#8220;Fu in riferimento a questa luce interiore che il Salvatore insegn\u00f2:&#8221; Il Regno di Dio \u00e8 dentro di te&#8221;.<\/span><\/p>\n<h2>L\u2019uomo naturale<\/h2>\n<p><span style=\"font-weight: 400;\">Allora perch\u00e9, se il nostro io interiore \u00e8 &#8220;<a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2017\/01\/31\/trovare-sostegno\/\" target=\"_blank\" rel=\"noopener\">la luce della verit\u00e0<\/a>&#8220;, a volte \u00e8 cos\u00ec difficile sentire la presenza di Dio? Le complicazioni derivano dalla nostra natura di esseri umani. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando veniamo sulla terra, &#8220;cadiamo&#8221; dal paradiso della presenza di Dio ed entriamo in un regno aspro che richiede sopravvivenza. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Perdiamo il nostro senso di armonia con la creazione e diventiamo invece un &#8220;io&#8221; in competizione con &#8220;gli altri&#8221;. Questo senso egoistico di s\u00e9, \u00e8 indicato negli studi di meditazione come l&#8217;ego.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;ego equivale grossomodo a ci\u00f2 che le Scritture chiamano l&#8217;uomo naturale. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Proprio come i maestri di meditazione hanno identificato l&#8217;ego o &#8220;falso s\u00e9&#8221; come la cosa che ci separa dalla presenza di Dio, il Libro di Mormon descrive l&#8217;uomo naturale come &#8220;nemico di Dio&#8221;, o in altre parole, la cosa che crea inimicizia tra noi stessi e la nostra origine divina. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dobbiamo &#8220;mettere via l&#8217;uomo naturale e diventare santi attraverso l&#8217;espiazione di Cristo il Signore&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gli istinti con cui siamo nati fanno s\u00ec che l&#8217;uomo naturale reagisca rapidamente a situazioni spiacevoli. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Qualcuno ci insulta e noi ci sentiamo offesi prima che la nostra istruzione religiosa ci dica che non dovremmo esserlo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se qualcuno ci fa del male, noi desideriamo ferirlo. Qualcosa ci spaventa e noi vogliamo scappare o combattere. Stimolo, risposta. Azione, reazione.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nella tradizione meditativa, i bisogni naturali e le paure dell&#8217;ego sono chiamati &#8220;attaccamenti&#8221; e sono individuati come la causa principale della sofferenza umana e dell&#8217;impedimento del progresso spirituale. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il Salvatore si riferiva agli attaccamenti come a dei fardelli che ci inducono ad essere &#8220;carichi pesanti&#8221; e a lavorare faticosamente sotto il loro peso e, ci ha insegnato a vivere senza. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Egli invit\u00f2 il giovane ricco a liberarsi dalle sue ricchezze. Egli mise in dubbio il bisogno di Marta di essere &#8220;attenta a molte cose\u201d. Egli disse: &#8220;Non pensare al domani&#8221;.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gli attaccamenti ci fanno vivere in uno stato di ansia ed insoddisfazione, perch\u00e9 avere bisogno di qualcosa \u00e8 temere di non averlo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La meditazione \u00e8 un metodo di allenamento spirituale che ci aiuta a eliminare i nostri attaccamenti e a risvegliare i nostri spiriti. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">I nostri corpi naturali e le nostre menti naturali sono come cavalli selvaggi, potenti e forti, ma potenzialmente pericolosi e distruttivi. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le nostre intelligenze spirituali sono come addestratori, inviati dalla presenza di Dio per guidare l&#8217;evoluzione di questo animale selvatico fino a diventare un tempio in cui lo Spirito pu\u00f2 dimorare.<\/span><\/p>\n<h2>E-spia-zio-ne<\/h2>\n<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/01\/atonement5.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-3416\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/01\/atonement5.jpg\" alt=\"espiazione e i peccati\" width=\"638\" height=\"360\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/01\/atonement5.jpg 638w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2016\/01\/atonement5-300x169.jpg 300w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/a>Esistono molte tradizioni e approcci diversi alla meditazione formale, non esiste un unico metodo \u201cgiusto&#8221; per meditare. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Suggerisco di ricercare approcci diversi con spirito di discernimento per trovare ci\u00f2 che funziona meglio per voi. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Anche i principi basilari della meditazione, quando applicati alla spiritualit\u00e0 quotidiana, possono essere trasformativi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il piccolo spazio di silenzio sacro coltivato in meditazione \u00e8 un luogo potente in cui l&#8217;Espiazione pu\u00f2 funzionare. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Diventiamo &#8220;un tutt&#8217;uno&#8221; con Dio ogni volta che siamo consapevoli dell&#8217;uomo naturale e riportiamo la nostra attenzione alla grazia del Signore. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quando meditiamo, con &#8220;occhio [o attenzione] singolo alla gloria di Dio&#8221;, il nostro &#8220;intero corpo sar\u00e0 pieno di luce&#8221;.<\/span><\/p>\n<h2>Trovare la pace interiore<\/h2>\n<p><span style=\"font-weight: 400;\">L&#8217;Espiazione pu\u00f2 essere vista come qualcosa che brucia dentro il nostro essere le energie pi\u00f9 oscure dell\u2019uomo Naturale, mentre riuniamo la nostra luce interiore con la luce del Salvatore. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo processo \u00e8 un percorso in salita che si autoalimenta: &#8220;colui che riceve la luce e continua in Dio riceve pi\u00f9 luce; e quella luce diventa sempre pi\u00f9 brillante fino al giorno perfetto\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo afflusso di luce consente alla grazia di fluire, l\u00e0 dove non spuntiamo liste di comandamenti, o ci deprimiamo con battute di arresto, o siamo ossessionati dal perfezionismo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nella vita meditativa la nostra \u201cfiducia si rafforza alla presenza di Dio\u201d perch\u00e9 quando pratichiamo, dimorando nella luce per alcuni minuti ogni giorno e poi ritorniamo a quella luce ogni volta che divaghiamo, l\u2019abitudine si interiorizzer\u00e0. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo processo di santificazione consente la trasformazione del corpo e della mente fino a quando finalmente \u201cmettiamo via\u201d l\u2019uomo naturale e \u201cdiventiamo Santi attraverso l\u2019Espiazione di Cristo\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Questo articolo \u00e8 stato originariamente scritto da S<i>heldon Lawrence<\/i> ed \u00e8 stato pubblicato su<\/span><a href=\"http:\/\/ldsliving.com\/\" target=\"_blank\" rel=\"nofollow noopener\"> <span style=\"font-weight: 400;\">ldsliving.com<\/span><\/a><span style=\"font-weight: 400;\">,<\/span><span style=\"font-weight: 400;\"> intitolato&nbsp;<\/span><a href=\"http:\/\/www.ldsliving.com\/Be-Still-Finding-Inner-Peace-and-a-Deeper-Connection-to-Christ-Through-Meditation\/s\/75731\" target=\"_blank\" rel=\"nofollow noopener\">Be Still: Finding Inner Peace and a Deeper Connection to Christ Through Meditation<\/a>.&nbsp;<span style=\"font-weight: 400;\">Italiano \u00a92018 LDS Living, A Division of Deseret Book Company | English \u00a92018 LDS Living, A Division of Deseret Book Company.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La meditazione \u00e8 l\u2019espressione dell\u2019anima, una porta sacra e segreta attraverso la quale si giunge alla presenza del Signore.<\/p>\n","protected":false},"author":52,"featured_media":6241,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[22],"tags":[956],"class_list":["post-6240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-vangelo","tag-spiritualita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo<\/title>\n<meta name=\"description\" content=\"La meditazione \u00e8 l\u2019espressione dell\u2019anima, una porta sacra e segreta attraverso la quale si giunge alla presenza del Signore tranne la pace interiore.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo\" \/>\n<meta property=\"og:description\" content=\"La meditazione \u00e8 l\u2019espressione dell\u2019anima, una porta sacra e segreta attraverso la quale si giunge alla presenza del Signore tranne la pace interiore.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-16T12:09:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-27T20:41:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sabrina Santalena\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sabrina Santalena\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/\"},\"author\":{\"name\":\"Sabrina Santalena\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/eebef437cab66bc3d152b09767480560\"},\"headline\":\"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo\",\"datePublished\":\"2018-02-16T12:09:03+00:00\",\"dateModified\":\"2018-06-27T20:41:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/\"},\"wordCount\":1120,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/02\\\/Trovare-la-pace-interiore.jpeg\",\"keywords\":[\"spiritualit\u00e0\"],\"articleSection\":[\"Vangelo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/\",\"name\":\"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/02\\\/Trovare-la-pace-interiore.jpeg\",\"datePublished\":\"2018-02-16T12:09:03+00:00\",\"dateModified\":\"2018-06-27T20:41:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/eebef437cab66bc3d152b09767480560\"},\"description\":\"La meditazione \u00e8 l\u2019espressione dell\u2019anima, una porta sacra e segreta attraverso la quale si giunge alla presenza del Signore tranne la pace interiore.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/02\\\/Trovare-la-pace-interiore.jpeg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/02\\\/Trovare-la-pace-interiore.jpeg\",\"width\":948,\"height\":542,\"caption\":\"Trovare la pace interiore\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/02\\\/16\\\/trovare-la-pace-interiore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/eebef437cab66bc3d152b09767480560\",\"name\":\"Sabrina Santalena\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5401ba7b44665fbe582e5a5ad731919465ad68b05d809122dd4103f14db5a7c8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5401ba7b44665fbe582e5a5ad731919465ad68b05d809122dd4103f14db5a7c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5401ba7b44665fbe582e5a5ad731919465ad68b05d809122dd4103f14db5a7c8?s=96&d=mm&r=g\",\"caption\":\"Sabrina Santalena\"},\"description\":\"Sabrina vive in Toscana a due passi dal mare, \u00e8 diplomata in pianoforte e ha studiato composizione presso l\u2019Istituto Superiore di Alta formazione artistica e musicale \u201cPietro Mascagni\u201d. Ha molti interessi fra i quali, oltre a quelli musicali, la scrittura creativa, fare sport fra la natura e viaggiare per conoscere nuove lingue e culture. Ha vissuto importanti esperienze lavorative sia in Italia che all\u2019estero. Ha svolto volontariato come soccorritrice del 118 e presso l\u2019Unione Italiana Ciechi e Ipovedenti Onlus. Ha servito come missionaria in Inghilterra e sta tuttora svolgendo incarichi per la Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi giorni di cui \u00e8 felice di far parte. Il Vangelo di Ges\u00f9 Cristo le ha donato molto arricchendo la sua vita, per questo desidera condividerlo per un arricchimento comune di valori spirituali, sociali, culturali e di fede.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/sabrina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo","description":"La meditazione \u00e8 l\u2019espressione dell\u2019anima, una porta sacra e segreta attraverso la quale si giunge alla presenza del Signore tranne la pace interiore.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/","og_locale":"it_IT","og_type":"article","og_title":"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo","og_description":"La meditazione \u00e8 l\u2019espressione dell\u2019anima, una porta sacra e segreta attraverso la quale si giunge alla presenza del Signore tranne la pace interiore.","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/","og_site_name":"gesucristo.org","article_published_time":"2018-02-16T12:09:03+00:00","article_modified_time":"2018-06-27T20:41:03+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg","type":"image\/jpeg"}],"author":"Sabrina Santalena","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Sabrina Santalena","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/"},"author":{"name":"Sabrina Santalena","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/eebef437cab66bc3d152b09767480560"},"headline":"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo","datePublished":"2018-02-16T12:09:03+00:00","dateModified":"2018-06-27T20:41:03+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/"},"wordCount":1120,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg","keywords":["spiritualit\u00e0"],"articleSection":["Vangelo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/","name":"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg","datePublished":"2018-02-16T12:09:03+00:00","dateModified":"2018-06-27T20:41:03+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/eebef437cab66bc3d152b09767480560"},"description":"La meditazione \u00e8 l\u2019espressione dell\u2019anima, una porta sacra e segreta attraverso la quale si giunge alla presenza del Signore tranne la pace interiore.","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/02\/Trovare-la-pace-interiore.jpeg","width":948,"height":542,"caption":"Trovare la pace interiore"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Trovare la pace interiore e una connessione pi\u00f9 profonda con Cristo"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/eebef437cab66bc3d152b09767480560","name":"Sabrina Santalena","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/5401ba7b44665fbe582e5a5ad731919465ad68b05d809122dd4103f14db5a7c8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5401ba7b44665fbe582e5a5ad731919465ad68b05d809122dd4103f14db5a7c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5401ba7b44665fbe582e5a5ad731919465ad68b05d809122dd4103f14db5a7c8?s=96&d=mm&r=g","caption":"Sabrina Santalena"},"description":"Sabrina vive in Toscana a due passi dal mare, \u00e8 diplomata in pianoforte e ha studiato composizione presso l\u2019Istituto Superiore di Alta formazione artistica e musicale \u201cPietro Mascagni\u201d. Ha molti interessi fra i quali, oltre a quelli musicali, la scrittura creativa, fare sport fra la natura e viaggiare per conoscere nuove lingue e culture. Ha vissuto importanti esperienze lavorative sia in Italia che all\u2019estero. Ha svolto volontariato come soccorritrice del 118 e presso l\u2019Unione Italiana Ciechi e Ipovedenti Onlus. Ha servito come missionaria in Inghilterra e sta tuttora svolgendo incarichi per la Chiesa di Ges\u00f9 Cristo dei Santi degli Ultimi giorni di cui \u00e8 felice di far parte. Il Vangelo di Ges\u00f9 Cristo le ha donato molto arricchendo la sua vita, per questo desidera condividerlo per un arricchimento comune di valori spirituali, sociali, culturali e di fede.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/sabrina\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/6240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=6240"}],"version-history":[{"count":3,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/6240\/revisions"}],"predecessor-version":[{"id":6244,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/6240\/revisions\/6244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/6241"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=6240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=6240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=6240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}