{"id":6520,"date":"2018-04-09T13:46:28","date_gmt":"2018-04-09T11:46:28","guid":{"rendered":"https:\/\/it.elds.org\/gesu-cristo-org\/?p=6520"},"modified":"2018-07-26T13:00:02","modified_gmt":"2018-07-26T11:00:02","slug":"perche-mentiamo-a-noi-stessi","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/","title":{"rendered":"Perch\u00e9 mentiamo a noi stessi"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-6523 size-full\" title=\"perch\u00e9 mentiamo\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg\" alt=\"mentire a noi stessi\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi-300x172.jpg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi-768x439.jpg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>Talvolta mentiamo a noi stessi senza volerlo, convincendoci erroneamente delle nostre verit\u00e0. Recentemente ho sentito mio fratello raccontare una storia su una diga straordinaria che ho progettato e costruito nel torrente dietro casa nostra. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il lago artificiale risultante ha fornito molte ore di divertimento per i bambini del vicinato. \u00c8 stato un trionfo dell&#8217;ingegneria!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il problema \u00e8 che, nella versione della storia di mio fratello, lui ha progettato e costruito la diga. \u00c8 stata tutta sua l\u2019idea.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ero scioccato! Come poteva la sua memoria sbagliarsi cos\u00ec totalmente?<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Mentiamo senza sapere che lo stiamo facendo<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Tendiamo a pensare ai nostri ricordi come video fedeli della realt\u00e0. &#8220;Lo ricordo chiaramente, come se fosse successo ieri.&#8221;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Spesso ci sbagliamo, specialmente quando la memoria riguarda qualcosa che ci interessa. Potremmo dire che la nostra memoria \u00e8 nemica della verit\u00e0. Il problema \u00e8 particolarmente evidente con il ricordo di esperienze emotive: momenti in cui siamo stati feriti o maltrattati.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In tutti i casi, la memoria \u00e8 pi\u00f9 vicina al racconto creativo che alla versione reale. Prendiamo alcune percezioni e le colleghiamo insieme alle nostra priorit\u00e0 e alle nostre ipotesi al fine di creare la storia che ha senso per noi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Di solito raccontiamo storie che ci fanno sembrare buoni e fanno sembrare cattivi i nostri nemici. Cambiamo la storia in modi importanti senza renderci conto che lo stiamo facendo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mi piace il modo in cui due famosi psicologi l\u2019hanno detto:<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Tra la menzogna consapevole per ingannare gli altri e l&#8217;auto-giustificazione inconscia per ingannare noi stessi giace un&#8217; affascinante linea di demarcazione, circondata da quella memoria storica inaffidabile, egoista. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">I ricordi sono spesso sfoltiti e plasmati da pregiudizi egocentrici che offuscano i confini degli eventi passati, attenuano la colpevolezza e distorcono ci\u00f2 che \u00e8 realmente accaduto. . . &nbsp;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nel corso del tempo, mentre le distorsioni egoistiche della memoria entrano in gioco e dimentichiamo o distorciamo eventi del passato, potremmo arrivare gradualmente a credere alle nostre stesse menzogne.&#8221;(Tavris &amp; Aronson, Gli errori furono fatti (ma non da <\/span><span style=\"font-weight: 400;\">Me<\/span><span style=\"font-weight: 400;\">), 2007, pagina 6)<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Mentiamo senza sapere che lo stiamo facendo. Mentiamo per proteggere la nostra percezione di noi stessi.<\/span><\/p>\n<h2>Riconoscere che possiamo mentire a noi stessi<\/h2>\n<p><span style=\"font-weight: 400;\">Jonathan Haidt, il brillante psicologo sociale ha osservato:<\/span><\/p>\n<blockquote><p><span style=\"font-weight: 400;\">&#8220;Tutti commettiamo atti egoistici e miopi, ma il nostro avvocato interno si assicura che non incolpiamo noi stessi o i nostri alleati per essi. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Siamo cos\u00ec convinti della nostra stessa virt\u00f9, ma siamo pronti a vedere pregiudizi, avidit\u00e0 e doppiezza negli altri. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Spesso ci ricrediamo in seguito alle motivazioni degli altri, ma con l&#8217;intensificarsi di ogni conflitto iniziamo a esagerare grossolanamente, tessiamo una storia in cui la pura virt\u00f9 (da parte nostra) \u00e8 in lotta con il puro vizio (da parte degli altri)&#8221;. (Happiness Hypothesis, 2006, p. 73).<\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">Capire che i nostri ricordi non sono sempre attendibili pu\u00f2 aiutarci a capire perch\u00e9 i risentimenti possono bruciare per decenni, perch\u00e9 le relazioni si disgregano e perch\u00e9 ci sono cos\u00ec tanti disaccordi nelle riunioni di famiglia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Siamo sicuri che le nostre storie abbiano ragione, anche se contraddicono l&#8217;esperienza delle altre persone nelle nostre vite.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Non esiste una verit\u00e0 affidabile?<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Se siamo umili, potremmo essere tentati dalla disperazione. &#8220;Non posso fidarmi di nessuno, nemmeno dei miei ricordi? Ero cos\u00ec sicuro che fossero accurati! &#8220;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Piuttosto che disperare, \u00e8 meglio essere aperti. Riconoscendo che abbiamo solo una prospettiva sulla storia e che abbiamo colmato qualsiasi lacuna con le nostre percezioni e preferenze, possiamo essere aperti alle storie di altre persone. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Possiamo chiedere: &#8220;Cosa ti ricordi?&#8221;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Joseph Smith ha dato un bellissimo esempio di questo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ha detto che &#8220;quando un nemico raccontava una storia scandalosa su di lui, cosa che succedeva spesso, prima di emettere un giudizio si fermava e lasciava che la sua mente tornasse all&#8217;ora, al luogo e all&#8217;ambientazione della storia per vedere se qualche parola o azione avventata avesse fornito involontariamente la base su cui era stata costruita la storia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se scopriva di averlo fatto, lo ammetteva nel suo cuore e poi perdonava il suo nemico e si sentiva grato di aver ricevuto un avvertimento di una debolezza che non sapeva di possedere. &#8220;(Jesse W. Crosby in Andrus and Andrus, 1974, loro conoscevano il Profeta).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prendete nota quando iniziate a scavare nei vostri ricordi con un obiettivo specifico in mente, se questo obiettivo \u00e8 di scagionare voi stessi o condannare qualcun altro. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Guardate i vostri ricordi con compassione. Riconoscete che le persone che vi hanno ferito stavano facendo del loro meglio. Riconoscete che i nostri motivi sono spesso imperfetti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il <a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/02\/16\/trovare-la-pace-interiore\/\" target=\"_blank\" rel=\"noopener\">comandamento di Ges\u00f9<\/a> di amarsi l&#8217;un l&#8217;altro include la volont\u00e0 di vedere il bene negli altri, di ascoltarli, di imparare da loro e di perdonarli essendo umani quanto noi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dio non ha inteso che usiamo i nostri ricordi per condannare le persone &nbsp;per i loro sbagli. Vorrebbe che usiamo la memoria per conservare la bont\u00e0 e la felicit\u00e0 &#8211; per ricordare i Suoi sacri doni. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Guardate le opportunit\u00e0 per conservare la bont\u00e0 e avere compassione per l&#8217;imperfezione.<\/span><\/p>\n<p><b>Applicazioni<\/b><span style=\"font-weight: 400;\">:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mentre leggete queste idee, pensate che la vostra memoria abbia avuto qualcuno di questi problemi? Lo Spirito vi invita a capire e a perdonare?<\/span><i><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Questo articolo \u00e8 stato scritto da Wallace Goddard ed \u00e8 stato pubblicato su <\/span><a href=\"https:\/\/ldsmag.com\/why-we-lie-to-ourselves\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">ldsmag.com.<\/span><\/a><span style=\"font-weight: 400;\"> Questo articolo \u00e8 stato tradotto da Nadia Manzaro.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ci potremmo sorprendere a mentire a noi stessi per difenderci dagli altri, ma dovremmo sempre chiederci se i nostri ricordi sono fedeli alla realt\u00e0.<\/p>\n","protected":false},"author":50,"featured_media":6523,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[953,432],"tags":[964],"class_list":["post-6520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articoli-consigliati","category-come-viviamo","tag-cristianesimo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perch\u00e9 mentiamo a noi stessi. La nostra memoria \u00e8 nemica della verit\u00e0?<\/title>\n<meta name=\"description\" content=\"Perch\u00e9 mentiamo a noi stessi? Ci potremmo sorprendere a mentire a noi stessi per difenderci dagli altri, ma dovremmo sempre chiederci se i nostri ricordi sono fedeli alla realt\u00e0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 mentiamo a noi stessi. La nostra memoria \u00e8 nemica della verit\u00e0?\" \/>\n<meta property=\"og:description\" content=\"Perch\u00e9 mentiamo a noi stessi? Ci potremmo sorprendere a mentire a noi stessi per difenderci dagli altri, ma dovremmo sempre chiederci se i nostri ricordi sono fedeli alla realt\u00e0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-09T11:46:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-26T11:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nadia Manzaro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nadia Manzaro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/\"},\"author\":{\"name\":\"Nadia Manzaro\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/e55b196fc0de07aa7f930c2db2c08e63\"},\"headline\":\"Perch\u00e9 mentiamo a noi stessi\",\"datePublished\":\"2018-04-09T11:46:28+00:00\",\"dateModified\":\"2018-07-26T11:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/\"},\"wordCount\":866,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/04\\\/mentiamo-a-noi-stessi.jpg\",\"keywords\":[\"cristianesimo\"],\"articleSection\":[\"Articoli consigliati\",\"Come viviamo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/\",\"name\":\"Perch\u00e9 mentiamo a noi stessi. La nostra memoria \u00e8 nemica della verit\u00e0?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/04\\\/mentiamo-a-noi-stessi.jpg\",\"datePublished\":\"2018-04-09T11:46:28+00:00\",\"dateModified\":\"2018-07-26T11:00:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/e55b196fc0de07aa7f930c2db2c08e63\"},\"description\":\"Perch\u00e9 mentiamo a noi stessi? Ci potremmo sorprendere a mentire a noi stessi per difenderci dagli altri, ma dovremmo sempre chiederci se i nostri ricordi sono fedeli alla realt\u00e0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/04\\\/mentiamo-a-noi-stessi.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2018\\\/04\\\/mentiamo-a-noi-stessi.jpg\",\"width\":948,\"height\":542,\"caption\":\"perch\u00e9 mentiamo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2018\\\/04\\\/09\\\/perche-mentiamo-a-noi-stessi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch\u00e9 mentiamo a noi stessi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/e55b196fc0de07aa7f930c2db2c08e63\",\"name\":\"Nadia Manzaro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/345d3043b13e55a14c1517f46db1c1798bee3cbd45481c85487ada37f512a191?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/345d3043b13e55a14c1517f46db1c1798bee3cbd45481c85487ada37f512a191?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/345d3043b13e55a14c1517f46db1c1798bee3cbd45481c85487ada37f512a191?s=96&d=mm&r=g\",\"caption\":\"Nadia Manzaro\"},\"description\":\"Nadia \u00e8 laureata in Scienze e Tecnologie Agrarie; dopo la laurea ha conseguito due master e ha insegnato per un certo periodo alla scuola superiore. Il suo desiderio \u00e8 di poter tornare a insegnare. \u00a0E\u2019 stata anche un\u2019insegnante nella Societ\u00e0 di Soccorso, all\u2019Istituto e in Primaria. Ama i bambini e soprattutto le sue due principesse. Nel tempo libero le piace frequentare corsi di pasticceria, prendersi cura delle sue gattine e stare in campagna. Ama il Vangelo e ha una testimonianza di Ges\u00f9 Cristo, di cui continua a portare testimonianza, sin dai tempi della missione in Inghilterra.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/nadia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perch\u00e9 mentiamo a noi stessi. La nostra memoria \u00e8 nemica della verit\u00e0?","description":"Perch\u00e9 mentiamo a noi stessi? Ci potremmo sorprendere a mentire a noi stessi per difenderci dagli altri, ma dovremmo sempre chiederci se i nostri ricordi sono fedeli alla realt\u00e0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/","og_locale":"it_IT","og_type":"article","og_title":"Perch\u00e9 mentiamo a noi stessi. La nostra memoria \u00e8 nemica della verit\u00e0?","og_description":"Perch\u00e9 mentiamo a noi stessi? Ci potremmo sorprendere a mentire a noi stessi per difenderci dagli altri, ma dovremmo sempre chiederci se i nostri ricordi sono fedeli alla realt\u00e0.","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/","og_site_name":"gesucristo.org","article_published_time":"2018-04-09T11:46:28+00:00","article_modified_time":"2018-07-26T11:00:02+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg","type":"image\/jpeg"}],"author":"Nadia Manzaro","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Nadia Manzaro","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/"},"author":{"name":"Nadia Manzaro","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/e55b196fc0de07aa7f930c2db2c08e63"},"headline":"Perch\u00e9 mentiamo a noi stessi","datePublished":"2018-04-09T11:46:28+00:00","dateModified":"2018-07-26T11:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/"},"wordCount":866,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg","keywords":["cristianesimo"],"articleSection":["Articoli consigliati","Come viviamo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/","name":"Perch\u00e9 mentiamo a noi stessi. La nostra memoria \u00e8 nemica della verit\u00e0?","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg","datePublished":"2018-04-09T11:46:28+00:00","dateModified":"2018-07-26T11:00:02+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/e55b196fc0de07aa7f930c2db2c08e63"},"description":"Perch\u00e9 mentiamo a noi stessi? Ci potremmo sorprendere a mentire a noi stessi per difenderci dagli altri, ma dovremmo sempre chiederci se i nostri ricordi sono fedeli alla realt\u00e0.","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2018\/04\/mentiamo-a-noi-stessi.jpg","width":948,"height":542,"caption":"perch\u00e9 mentiamo"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2018\/04\/09\/perche-mentiamo-a-noi-stessi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"Perch\u00e9 mentiamo a noi stessi"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/e55b196fc0de07aa7f930c2db2c08e63","name":"Nadia Manzaro","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/345d3043b13e55a14c1517f46db1c1798bee3cbd45481c85487ada37f512a191?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/345d3043b13e55a14c1517f46db1c1798bee3cbd45481c85487ada37f512a191?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/345d3043b13e55a14c1517f46db1c1798bee3cbd45481c85487ada37f512a191?s=96&d=mm&r=g","caption":"Nadia Manzaro"},"description":"Nadia \u00e8 laureata in Scienze e Tecnologie Agrarie; dopo la laurea ha conseguito due master e ha insegnato per un certo periodo alla scuola superiore. Il suo desiderio \u00e8 di poter tornare a insegnare. \u00a0E\u2019 stata anche un\u2019insegnante nella Societ\u00e0 di Soccorso, all\u2019Istituto e in Primaria. Ama i bambini e soprattutto le sue due principesse. Nel tempo libero le piace frequentare corsi di pasticceria, prendersi cura delle sue gattine e stare in campagna. Ama il Vangelo e ha una testimonianza di Ges\u00f9 Cristo, di cui continua a portare testimonianza, sin dai tempi della missione in Inghilterra.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/nadia\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/6520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=6520"}],"version-history":[{"count":4,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/6520\/revisions"}],"predecessor-version":[{"id":6525,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/6520\/revisions\/6525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/6523"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=6520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=6520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=6520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}