{"id":7129,"date":"2019-01-16T12:16:04","date_gmt":"2019-01-16T11:16:04","guid":{"rendered":"https:\/\/it.elds.org\/gesu-cristo-org\/?p=7129"},"modified":"2019-01-16T12:16:04","modified_gmt":"2019-01-16T11:16:04","slug":"limportanza-delle-preghiere-infantili","status":"publish","type":"post","link":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/","title":{"rendered":"L&#8217;importanza delle preghiere infantili"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-7130\" src=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg\" alt=\"preghiere infantili\" width=\"948\" height=\"542\" srcset=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg 948w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili-300x172.jpg 300w, https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili-768x439.jpg 768w\" sizes=\"(max-width: 948px) 100vw, 948px\" \/><\/a>Mi sono reso conto, di recente, di quanto siano importanti le preghiere infantili. Mi spiego meglio. Di solito, io provo a fermarmi un attimo prima di pregare. Provo a pensare a quello che sto facendo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> A cosa significhi parlare con Dio. La notte scorsa, mentre mi inginocchiavo, mi sono preso un momento prima di iniziare, facendo alcuni respiri lenti.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Poi ho iniziato a pregare e la prima cosa che mi \u00e8 venuta in mente era una preoccupazione banale per il mio lavoro. In un lampo, mi sono visto dall&#8217;esterno e l&#8217;assurdit\u00e0 di ci\u00f2 che stavo facendo mi ha travolto: \u201cMi inginocchio, comunico con il divino e voglio parlare della mia carriera!\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ho iniziato a ridere di me stesso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">&#8220;Allora&#8221; ho pensato &#8220;tu ti inginocchi davanti al creatore di mondi e stelle e galassie e&#8230; vuoi parlare del tuo lavoro giornaliero?&#8221;. Mi \u00e8 sembrato strano, ma c&#8217;era anche dell\u2019amarezza e un retrogusto di vergogna.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prima di quella sera, prima di pregare, avevo letto per mio figlio. Avevamo appena iniziato Ender&#8217;s Game, e nel capitolo 1 si parla del \u201cmonitor\u201d. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c8 un piccolo impianto futuristico che viene usato per tracciare ogni percezione e sentimento dei bambini che sono candidati alla Scuola della Guerra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Orson Scott Card \u00e8 un grande scrittore di fantascienza e ci\u00f2 significa che ha dovuto imparare a padroneggiare l&#8217;arte dell&#8217;esposizione. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sa dare al lettore abbastanza informazioni per renderlo curioso, ma anche per capire cosa stia succedendo. E cos\u00ec non spiega mai nulla. Non dice \u201cEcco cos\u2019\u00e8 il monitor!\u201d, ma bisogna capirlo dagli spunti e dal contesto. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">E questo \u00e8 qualcosa in cui gli adulti sono bravi. Abbiamo molta pratica. Ma i bambini di dieci anni? Non ne hanno cos\u00ec tanta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E cos\u00ec mio figlio &#8211; infinitamente curioso di sapere come funziona il mondo &#8211; continuava a interrompermi per chiedere che cosa fosse il monitor. Ed io continuavo a rispondergli: &#8220;Fai solo attenzione&#8221; oppure &#8220;Non dovresti sapere ancora di cosa si tratti&#8221; o anche &#8220;L&#8217;autore sa che non lo sai. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">E questo fa parte della storia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Lo spiegher\u00e0, ma non te ne renderai conto se non presti attenzione, quindi andiamo con calma!&#8221;. La prima volta che mi ha interrotto ero paziente, ma alla terza o quarta volta quella pazienza era finita. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">E lui si \u00e8 buttato sotto le coperte e si \u00e8 nascosto, mentre io continuavo a leggere.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">In tutto quel periodo ho pensato a quanto, nel corso degli anni, io mi sia sentito frustrato con i miei figli e a tutte le volte in cui, poi, mi sono pentito del fatto che quello che mi frustrava altro non era che un comportamento che definisce l\u2019infanzia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Pu\u00f2 essere incredibilmente frustrante dover dire un centinaio di volte al tuo bambino di mettersi le scarpe e, poi, salire in macchina mentre la sua attenzione continua a passare da una cosa all\u2019altra, come un cucciolo iperattivo, e sale in macchina soltanto in calzini.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ma essere attenti \u00e8 l&#8217;arte di sopprimere lo stimolo. \u00c8 la sudata pratica di non vedere, non ascoltare e non pensare. Non potete volere che vostro figlio sia pi\u00f9 bravo a prestare attenzione, senza volere che smetta di sentire la meravigliosa novit\u00e0 del suo mondo. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prestare attenzione va bene per gli adulti, ma lo volete davvero per il vostro bambino? In questo momento?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">I bambini si distraggono facilmente perch\u00e9 il mondo \u00e8 ancora cos\u00ec nuovo per loro. Si distraggono perch\u00e9 stanno imparando. La distrazione \u00e8 il nocciolo della meraviglia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">I genitori ordinari a volte sono cattivi, a volte sono buoni. Quando siamo cattivi genitori, potremmo essere frustrati dalle stesse cose che abbiamo a cuore quando siamo buoni genitori. Come i bambini distratti: fastidiosi e meravigliosi.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mio figlio non conosceva le regole dell&#8217;esposizione della fantascienza. Come cattivo padre, ero frustrato dal fatto che non l&#8217;avesse capito. Come buon padre, ero onorato di essere presente, mentre lo imparava per la prima volta. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ero davvero onorato. Ho scoperto che quello che mi faceva desiderare di strapparmi i capelli era la stessa cosa che apprezzavo nel mio cuore.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ed ecco quello che ho pensato: il Padre celeste \u00e8 un buon padre. Sempre.<\/span><\/p>\n<h2>Le preghiere infantili<\/h2>\n<p><span style=\"font-weight: 400;\">E cos\u00ec, mentre ero l\u00ec inginocchiato, a ridere di me stesso e della mia preghiera infantile, con le mie preoccupazioni infantili, ho avuto un secondo pensiero. &#8220;Bene, di cosa ho intenzione di parlare? C\u2019\u00e8 qualcosa per la quale pregare che abbia davvero un intrinseco significato cosmico?&#8221;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Spoiler: no, non ce l\u2019ho.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Nella mia vita non c&#8217;\u00e8 nulla che possa eguagliare la maestosa rotazione della Via Lattea o le complesse sottigliezze delle leggi fisiche delicatamente intrecciate che definiscono il tessuto dello spazio e del tempo nel loro significato solenne e incontestabile. Sono solo un ragazzo insignificante, uno tra innumerevoli altri.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Per uno standard oggettivo, sono insignificante. Quindi, fintanto che ogni aspetto della mia vita sembra insignificante, perch\u00e9 mi preoccupo per quale aspetto insignificante di essa <a href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2015\/04\/23\/il-potere-della-preghiera\/\" target=\"_blank\" rel=\"noopener\">scelgo di rivolgermi a Dio<\/a>?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">E poi oggi ho letto quanto segue, scritto dall&#8217;anziano Marion G. Romney nel libro \u201cI principi di base della Chiesa, del benessere\u201d:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cIl Signore \u00e8 interessato a tutto ci\u00f2 che facciamo nella nostra vita: alle nostre famiglie, al nostro lavoro e al nostro sviluppo personale\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">C&#8217;\u00e8 una buona domanda che uno scettico pu\u00f2 chiedere ad un credente: perch\u00e9 un creatore onnipotente dovrebbe prendersi cura di te in particolare? <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Perch\u00e9 l&#8217;Architetto dell&#8217;universo dovrebbe prestare attenzione individuale a questa o quella creatura mortale che inciampa ciecamente sulla superficie di un piccolo mondo? \u00c8 un bell\u2019argomento di cui parlare.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Beh, perch\u00e9 ti dovrebbe importare quando un bambino viene da te con un telefono giocattolo? Quale buona ragione ti fa prendere il telefono e ti fa fingere di avere una conversazione? <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assolutamente nessuna. E lo facciamo tutti, ognuno di noi, anche se non sappiamo di chi sia quel bambino.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#8217;argomento dall&#8217;essere insignificanti \u00e8 una spada che taglia da entrambi i lati. Se inizi a pensare di essere insignificante, allora ti chiedi perch\u00e9 mai a Dio dovrebbe importare di te.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ma se hai una convinzione nella tua anima &#8211; o anche solo un debole sussurro di speranza &#8211; che Dio si preoccupi davvero di te, allora tutto si trasforma in qualcosa. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">La totale e completa mancanza di equilibrio tra Dio e te \u00e8 ancora l\u00ec, ma non \u00e8 pi\u00f9 un gioco. Ora \u00e8 un mistero profondo quanto l&#8217;amore di un genitore per il proprio bambino ignaro, innocente ed in crescita.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il Padre celeste \u00e8 un buon padre. Sempre. Non \u00e8 mai impaziente con la nostra immaturit\u00e0 o la nostra costante distrazione per le cose banali. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il Padre celeste \u00e8 abbastanza saggio da non perdere mai un momento della nostra et\u00e0 e fa sempre tesoro del Suo ruolo nell&#8217;aiutarci ad imparare ed a crescere.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Non mi vergogno pi\u00f9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sono un figlio di Dio.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">Questo articolo \u00e8 stato scritto da Nathaniel Givens ed \u00e8 pubblicato sul sito<\/span><\/i><a href=\"https:\/\/ldsmag.com\/the-importance-of-our-childish-childlike-prayers\/?fbclid=IwAR33IJF-5cxu_eNdZRA0ZBy4IrIq0CzaCtklzJGsPL5XEf1rKc4vSJuo0MI\" target=\"_blank\" rel=\"nofollow noopener\"> <i><span style=\"font-weight: 400;\">ldsmag.com<\/span><\/i><\/a><i><span style=\"font-weight: 400;\">. Questo articolo \u00e8 stato tradotto da Cinzia Galasso.<\/span><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Noi siamo i figli del Padre Celeste e quando ci rivolgiamo a Lui veniamo sempre ascoltati anche se crediamo che le nostre preghiere siano infantili o banali.<\/p>\n","protected":false},"author":44,"featured_media":7130,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[7],"tags":[966],"class_list":["post-7129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dottrine","tag-preghiera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;importanza delle preghiere infantili<\/title>\n<meta name=\"description\" content=\"Noi siamo i figli del Padre Celeste e quando ci rivolgiamo a Lui veniamo sempre ascoltati anche se crediamo che le nostre preghiere infantili o banali.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;importanza delle preghiere infantili\" \/>\n<meta property=\"og:description\" content=\"Noi siamo i figli del Padre Celeste e quando ci rivolgiamo a Lui veniamo sempre ascoltati anche se crediamo che le nostre preghiere infantili o banali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/\" \/>\n<meta property=\"og:site_name\" content=\"gesucristo.org\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-16T11:16:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"542\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cinzia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cinzia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/\"},\"author\":{\"name\":\"Cinzia\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/ce134334ee9829422fabc907058b43bd\"},\"headline\":\"L&#8217;importanza delle preghiere infantili\",\"datePublished\":\"2019-01-16T11:16:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/\"},\"wordCount\":1142,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2019\\\/01\\\/Limportanza-delle-preghiere-infantili.jpg\",\"keywords\":[\"preghiera\"],\"articleSection\":[\"Dottrine\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/\",\"name\":\"L'importanza delle preghiere infantili\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2019\\\/01\\\/Limportanza-delle-preghiere-infantili.jpg\",\"datePublished\":\"2019-01-16T11:16:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/ce134334ee9829422fabc907058b43bd\"},\"description\":\"Noi siamo i figli del Padre Celeste e quando ci rivolgiamo a Lui veniamo sempre ascoltati anche se crediamo che le nostre preghiere infantili o banali.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#primaryimage\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2019\\\/01\\\/Limportanza-delle-preghiere-infantili.jpg\",\"contentUrl\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/files\\\/2019\\\/01\\\/Limportanza-delle-preghiere-infantili.jpg\",\"width\":948,\"height\":542,\"caption\":\"preghiere infantili\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/2019\\\/01\\\/16\\\/limportanza-delle-preghiere-infantili\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;importanza delle preghiere infantili\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/\",\"name\":\"gesucristo.org\",\"description\":\"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/#\\\/schema\\\/person\\\/ce134334ee9829422fabc907058b43bd\",\"name\":\"Cinzia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g\",\"caption\":\"Cinzia\"},\"description\":\"Cinzia \u00e8 un'impiegata ed una traduttrice. Ha una laurea in Scienze dell'Educazione e ha anche insegnato, per un paio di anni, a bambini della scuola materna, un lavoro che ha amato molto. E' stata un'insegnante nelle classi della Societ\u00e0 di Soccorso, delle Giovani Donne e dell'Istituto. Ha molti interessi: patchwork, quilling, oli essenziali. Le piace prendersi cura di s\u00e8 con soluzioni naturali. E' vegana e ama gli animali e la natura ed \u00e8 fermamente convinta che le creazioni di Dio siano sacre. E' una volontaria dell'ENPA, un'associazione italiana, per la protezione degli animali ed \u00e8 anche un membro di Greenpeace e del WWF. Ama passare il tempo con la sua famiglia e i suoi amici. Ama il vangelo di Ges\u00f9 Cristo e sa che le famiglie sono eterne.\",\"url\":\"https:\\\/\\\/it.elds.org\\\/gesu-cristo-org\\\/author\\\/cinzia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'importanza delle preghiere infantili","description":"Noi siamo i figli del Padre Celeste e quando ci rivolgiamo a Lui veniamo sempre ascoltati anche se crediamo che le nostre preghiere infantili o banali.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/","og_locale":"it_IT","og_type":"article","og_title":"L'importanza delle preghiere infantili","og_description":"Noi siamo i figli del Padre Celeste e quando ci rivolgiamo a Lui veniamo sempre ascoltati anche se crediamo che le nostre preghiere infantili o banali.","og_url":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/","og_site_name":"gesucristo.org","article_published_time":"2019-01-16T11:16:04+00:00","og_image":[{"width":948,"height":542,"url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg","type":"image\/jpeg"}],"author":"Cinzia","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Cinzia","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/"},"author":{"name":"Cinzia","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/ce134334ee9829422fabc907058b43bd"},"headline":"L&#8217;importanza delle preghiere infantili","datePublished":"2019-01-16T11:16:04+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/"},"wordCount":1142,"commentCount":0,"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg","keywords":["preghiera"],"articleSection":["Dottrine"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/","url":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/","name":"L'importanza delle preghiere infantili","isPartOf":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#primaryimage"},"image":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#primaryimage"},"thumbnailUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg","datePublished":"2019-01-16T11:16:04+00:00","author":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/ce134334ee9829422fabc907058b43bd"},"description":"Noi siamo i figli del Padre Celeste e quando ci rivolgiamo a Lui veniamo sempre ascoltati anche se crediamo che le nostre preghiere infantili o banali.","breadcrumb":{"@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#primaryimage","url":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg","contentUrl":"https:\/\/it.elds.org\/gesu-cristo-org\/files\/2019\/01\/Limportanza-delle-preghiere-infantili.jpg","width":948,"height":542,"caption":"preghiere infantili"},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/2019\/01\/16\/limportanza-delle-preghiere-infantili\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/gesu-cristo-org\/"},{"@type":"ListItem","position":2,"name":"L&#8217;importanza delle preghiere infantili"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#website","url":"https:\/\/it.elds.org\/gesu-cristo-org\/","name":"gesucristo.org","description":"Il sito gesucristo.org offre una visione allargata del vangelo restaurato di Ges\u00f9 Cristo e di come possiamo usarlo per vincere le sfide degli ultimi giorni, con consigli, esempi e storie edificanti.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/gesu-cristo-org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/it.elds.org\/gesu-cristo-org\/#\/schema\/person\/ce134334ee9829422fabc907058b43bd","name":"Cinzia","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/453a3b6b7fba71cb4f9fdcb60699e790d6c2d579f02116f4d33dae5b2732f4bb?s=96&d=mm&r=g","caption":"Cinzia"},"description":"Cinzia \u00e8 un'impiegata ed una traduttrice. Ha una laurea in Scienze dell'Educazione e ha anche insegnato, per un paio di anni, a bambini della scuola materna, un lavoro che ha amato molto. E' stata un'insegnante nelle classi della Societ\u00e0 di Soccorso, delle Giovani Donne e dell'Istituto. Ha molti interessi: patchwork, quilling, oli essenziali. Le piace prendersi cura di s\u00e8 con soluzioni naturali. E' vegana e ama gli animali e la natura ed \u00e8 fermamente convinta che le creazioni di Dio siano sacre. E' una volontaria dell'ENPA, un'associazione italiana, per la protezione degli animali ed \u00e8 anche un membro di Greenpeace e del WWF. Ama passare il tempo con la sua famiglia e i suoi amici. Ama il vangelo di Ges\u00f9 Cristo e sa che le famiglie sono eterne.","url":"https:\/\/it.elds.org\/gesu-cristo-org\/author\/cinzia\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/7129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/comments?post=7129"}],"version-history":[{"count":3,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/7129\/revisions"}],"predecessor-version":[{"id":7133,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/posts\/7129\/revisions\/7133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media\/7130"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/media?parent=7129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/categories?post=7129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/gesu-cristo-org\/wp-json\/wp\/v2\/tags?post=7129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}