{"id":974,"date":"2010-10-28T22:45:14","date_gmt":"2010-10-29T05:45:14","guid":{"rendered":"http:\/\/giuseppemartinengo.org\/?p=974"},"modified":"2010-10-28T22:45:14","modified_gmt":"2010-10-29T05:45:14","slug":"tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone","status":"publish","type":"post","link":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/","title":{"rendered":"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone"},"content":{"rendered":"<p>Questo \u00e8 il video della cerimonia completa del primo colpo di piccone per il <a class=\"external_link_tool\" href=\"http:\/\/giuseppemartinengo.org\/304\/il-tempio-mormone-di-draper-usa\">Tempio Mormone<\/a> di Roma.<\/p>\n<p>La cerimonia \u00e8 stata realizzata il giorno 23 di ottobre 2010 ed \u00e8 stata presieduta dal Presidente della <a class=\"external_link_tool\" href=\"http:\/\/romatempiomormone.com\/129\/matt-durazzani-riflette-tempio-mormone-di-roma\">Chiesa di Ges\u00f9 Cristo dei santi degli Ultimi Giorni<\/a>, Presidente Thomas S. Monson.<\/p>\n<p>Per gli italiani membri della Chiesa di <a href=\"http:\/\/www.chiesamormone.com\" class=\"external_link_tool\">Ges\u00f9<\/a> Cristo dei <a href=\"http:\/\/romatempiomormone.com\/129\/matt-durazzani-riflette-tempio-mormone-di-roma\" class=\"external_link_tool\">Santi degli Ultimi Giorni<\/a> (anche conosciuti come i <a href=\"http:\/\/it.mormon.wikia.com\/wiki\/Quello_che_credono_i_mormoni\" class=\"external_link_tool\">mormoni<\/a>), il sabato ha intessuto il ricco passato spirituale di questa citt\u00e0 con un futuro pieno di promesse e, aggiungono, opportunit\u00e0 eterne. Il presidente Thomas S. Monson presiedeva la cerimonia del primo colpo di piccone del futuro Tempio di Roma, Italia in costruzione su un sito prativo, nell\u2019angolo nord-est della citt\u00e0. <\/p>\n<p>Il Presidente Thomas S. Monson ha condiviso osservazioni e consigli prima di offrire una preghiera di ringraziamento e di dedicazione del sito del tempio e del progetto di costruzione. \u201cMiei cari fratelli e sorelle, non posso adeguatamente esprimervi la gioia che sento in questa occasione storica\u201d, ha detto. \u201cMentre contemplo il nostro caloroso benvenuto qui, in questa citt\u00e0, che \u00e8 cos\u00ec ricca di storia, compresa la storia del cristianesimo, il mio cuore \u00e8 colmo di gratitudine\u201d. <\/p>\n<p>Dopo la preghiera, il presidente Monson \u00e8 sceso dal podio, ha preso un badile e ha scavato una palata di terra per dare inizio alla costruzione del tempio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Questo \u00e8 il video della cerimonia completa del primo colpo di piccone per il Tempio Mormone di Roma. La cerimonia \u00e8 stata realizzata il giorno 23 di ottobre 2010 ed \u00e8 stata presieduta dal Presidente della Chiesa di Ges\u00f9 Cristo dei santi degli Ultimi Giorni, Presidente Thomas S. Monson. Per gli italiani membri della Chiesa [&hellip;]<\/p>\n","protected":false},"author":48,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22,30],"tags":[110,534,536,537],"class_list":["post-974","post","type-post","status-publish","format-standard","hentry","category-mormonismo","category-tempio-mormone","tag-chiesa-di-gesu-cristo-chiesa-mormone","tag-tempio-di-roma","tag-tempio-mormone","tag-tempio-mormone-di-roma","et-doesnt-have-format-content","et_post_format-et-post-format-standard"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone - Giovani Mormoni<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone - Giovani Mormoni\" \/>\n<meta property=\"og:description\" content=\"Questo \u00e8 il video della cerimonia completa del primo colpo di piccone per il Tempio Mormone di Roma. La cerimonia \u00e8 stata realizzata il giorno 23 di ottobre 2010 ed \u00e8 stata presieduta dal Presidente della Chiesa di Ges\u00f9 Cristo dei santi degli Ultimi Giorni, Presidente Thomas S. Monson. Per gli italiani membri della Chiesa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/\" \/>\n<meta property=\"og:site_name\" content=\"Giovani Mormoni\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-29T05:45:14+00:00\" \/>\n<meta name=\"author\" content=\"giovanimormoni-com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"giovanimormoni-com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/\"},\"author\":{\"name\":\"giovanimormoni-com\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/#\\\/schema\\\/person\\\/b4ea92441c2413ac871a07b80ce3bb9b\"},\"headline\":\"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone\",\"datePublished\":\"2010-10-29T05:45:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/\"},\"wordCount\":228,\"commentCount\":0,\"keywords\":[\"Chiesa di Ges\u00f9 Cristo (Chiesa Mormone)\",\"Tempio di Roma\",\"Tempio Mormone\",\"tempio mormone di roma\"],\"articleSection\":[\"Mormonismo\",\"Tempio Mormone\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/\",\"url\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/\",\"name\":\"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone - Giovani Mormoni\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/#website\"},\"datePublished\":\"2010-10-29T05:45:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/#\\\/schema\\\/person\\\/b4ea92441c2413ac871a07b80ce3bb9b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/2010\\\/10\\\/28\\\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/#website\",\"url\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/\",\"name\":\"Giovani Mormoni\",\"description\":\"Un blog mormone a proposito di religione, famiglia e attualit\u00e0\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/#\\\/schema\\\/person\\\/b4ea92441c2413ac871a07b80ce3bb9b\",\"name\":\"giovanimormoni-com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/508724513f51e439c3411fd3057dc8ea7f3e13a49ec4c71c7f33426322312886?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/508724513f51e439c3411fd3057dc8ea7f3e13a49ec4c71c7f33426322312886?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/508724513f51e439c3411fd3057dc8ea7f3e13a49ec4c71c7f33426322312886?s=96&d=mm&r=g\",\"caption\":\"giovanimormoni-com\"},\"url\":\"https:\\\/\\\/it.elds.org\\\/giovanimormoni-com\\\/author\\\/giovanimormoni-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone - Giovani Mormoni","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/","og_locale":"en_US","og_type":"article","og_title":"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone - Giovani Mormoni","og_description":"Questo \u00e8 il video della cerimonia completa del primo colpo di piccone per il Tempio Mormone di Roma. La cerimonia \u00e8 stata realizzata il giorno 23 di ottobre 2010 ed \u00e8 stata presieduta dal Presidente della Chiesa di Ges\u00f9 Cristo dei santi degli Ultimi Giorni, Presidente Thomas S. Monson. Per gli italiani membri della Chiesa [&hellip;]","og_url":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/","og_site_name":"Giovani Mormoni","article_published_time":"2010-10-29T05:45:14+00:00","author":"giovanimormoni-com","twitter_card":"summary_large_image","twitter_misc":{"Written by":"giovanimormoni-com","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/#article","isPartOf":{"@id":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/"},"author":{"name":"giovanimormoni-com","@id":"https:\/\/it.elds.org\/giovanimormoni-com\/#\/schema\/person\/b4ea92441c2413ac871a07b80ce3bb9b"},"headline":"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone","datePublished":"2010-10-29T05:45:14+00:00","mainEntityOfPage":{"@id":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/"},"wordCount":228,"commentCount":0,"keywords":["Chiesa di Ges\u00f9 Cristo (Chiesa Mormone)","Tempio di Roma","Tempio Mormone","tempio mormone di roma"],"articleSection":["Mormonismo","Tempio Mormone"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/","url":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/","name":"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone - Giovani Mormoni","isPartOf":{"@id":"https:\/\/it.elds.org\/giovanimormoni-com\/#website"},"datePublished":"2010-10-29T05:45:14+00:00","author":{"@id":"https:\/\/it.elds.org\/giovanimormoni-com\/#\/schema\/person\/b4ea92441c2413ac871a07b80ce3bb9b"},"breadcrumb":{"@id":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/it.elds.org\/giovanimormoni-com\/2010\/10\/28\/tempio-mormone-di-roma-video-della-cerimonia-del-primo-colpo-di-piccone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/it.elds.org\/giovanimormoni-com\/"},{"@type":"ListItem","position":2,"name":"Tempio Mormone di Roma: video completo della cerimonia del primo colpo di piccone"}]},{"@type":"WebSite","@id":"https:\/\/it.elds.org\/giovanimormoni-com\/#website","url":"https:\/\/it.elds.org\/giovanimormoni-com\/","name":"Giovani Mormoni","description":"Un blog mormone a proposito di religione, famiglia e attualit\u00e0","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/it.elds.org\/giovanimormoni-com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/it.elds.org\/giovanimormoni-com\/#\/schema\/person\/b4ea92441c2413ac871a07b80ce3bb9b","name":"giovanimormoni-com","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/508724513f51e439c3411fd3057dc8ea7f3e13a49ec4c71c7f33426322312886?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/508724513f51e439c3411fd3057dc8ea7f3e13a49ec4c71c7f33426322312886?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/508724513f51e439c3411fd3057dc8ea7f3e13a49ec4c71c7f33426322312886?s=96&d=mm&r=g","caption":"giovanimormoni-com"},"url":"https:\/\/it.elds.org\/giovanimormoni-com\/author\/giovanimormoni-com\/"}]}},"_links":{"self":[{"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/posts\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/comments?post=974"}],"version-history":[{"count":0,"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/posts\/974\/revisions"}],"wp:attachment":[{"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/media?parent=974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/categories?post=974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/it.elds.org\/giovanimormoni-com\/wp-json\/wp\/v2\/tags?post=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}